{"id":927,"date":"2024-12-18T12:13:00","date_gmt":"2024-12-18T12:13:00","guid":{"rendered":"https:\/\/tusnoticiasya.com\/?p=927"},"modified":"2025-01-21T13:56:56","modified_gmt":"2025-01-21T13:56:56","slug":"recuperan-inmueble-fiscal-usurpado-cerca-del-parque-mitre","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2024\/12\/18\/recuperan-inmueble-fiscal-usurpado-cerca-del-parque-mitre\/","title":{"rendered":"RECUPERAN INMUEBLE FISCAL USURPADO CERCA DEL PARQUE MITRE"},"content":{"rendered":"\n<p>Se trata de una de las usurpaciones emblem\u00e1ticas en pleno centro de la Capital provincial, que hoy finaliz\u00f3. El Fiscal de Estado Horacio Ortega, encabez\u00f3 el allanamiento y qued\u00f3 como depositario judicial. Continuar\u00e1n el proceso de recuperaci\u00f3n de bienes del Estado. &nbsp;<\/p>\n\n\n\n<p>El Fiscal de Estado, Horacio David Ortega encabez\u00f3 este mi\u00e9rcoles un operativo, junto al Procurador del Tesoro, Jos\u00e9 Roa, y con el apoyo de la polic\u00eda de Corrientes, donde se logr\u00f3 recuperar un inmueble fiscal usurpado hace a\u00f1os, ubicado sobre avenida Poncho Verde en intersecci\u00f3n con calle Rol\u00f3n.<\/p>\n\n\n\n<p>El terreno fiscal de uno 700 m2, que se encuentra en el denominado \u201ctri\u00e1ngulo\u201d, en medio del Parque Mitre y el barrio La Rosada, hab\u00eda sido usurpado hace d\u00e9cadas atr\u00e1s, por una mujer y en el mismo se hab\u00eda levantado una estructura que se explot\u00f3 comercialmente hasta algunos a\u00f1os atr\u00e1s.<\/p>\n\n\n\n<p>Las acciones judiciales llevadas a cabo ante el Juzgado de Instrucci\u00f3n N\u00b0 6, a cargo del juez C\u00e9sar Valenzuela, culminaron en favor del Estado Provincial, y se libr\u00f3 la orden de allanamiento y posterior entrega del inmueble al Fiscal de Estado como depositario.&nbsp;<\/p>\n\n\n\n<p>\u201cTenemos directrices claras del Gobernador Vald\u00e9s, para velar por los intereses del Estado provincial y defender sus bienes. En ese sentido, es que trabajamos d\u00eda tras d\u00eda, entendiendo que es necesario que existe orden en este tipo de cuestiones y se cumplan las normas vigentes, para continuar siendo una comunidad con paz social\u201d, explic\u00f3 Ortega.<\/p>\n\n\n\n<p>Las acciones judiciales se iniciaron en el a\u00f1o 2008, no obstante en el \u00faltimo periodo se hizo un seguimiento intensivo para lograr desalojar a quienes se instalaron en el predio, construyeron y usufructuaron un lugar que est\u00e1 previsto como un pulm\u00f3n de la ciudad.&nbsp;<\/p>\n\n\n\n<p>\u201cVamos a seguir en este sentido, porque no podemos permitir que un delito como la usurpaci\u00f3n quede impune. Existen muchos terrenos del Estado en igual situaci\u00f3n, y vamos a ir por ellos. Accionamos judicialmente y buscaremos, que se produzcan los desalojos correspondientes lo antes posible, y que sea el Poder Ejecutivo quien disponga que hacer con ellos\u201d, grafi\u00f3 Ortega.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Las actuaciones<\/strong><\/h2>\n\n\n\n<p>En el a\u00f1o 2009 y ante la constataci\u00f3n de un delito de usurpaci\u00f3n de terrenos del Estado provincia, la Fiscal\u00eda de Estado hizo la pertinente denuncia por usurpaci\u00f3n, que recay\u00f3 en el Juzgado de Instrucci\u00f3n &nbsp;6. Mediante el expediente N\u00b0 14369, que incluy\u00f3 a todos los inmuebles de la Manzana 35 sobre Avenida Pujol.&nbsp;<\/p>\n\n\n\n<p>En ese cado result\u00f3 imputada una mujer que aparec\u00eda como la responsable de la acci\u00f3n. Con el tiempo algunos de los imputados iniciaron juicios de Prescripci\u00f3n Adquisitiva, de los cuales uno solo tuvo hasta el momento resoluci\u00f3n definitiva.&nbsp;<\/p>\n\n\n\n<p>En este inmueble en particular, el Juez de Instrucci\u00f3n sustituto del Juzgado N\u00b0 6, Cesar Valenzuela emiti\u00f3 la orden de recuperaci\u00f3n del bien para el Estado dentro de la causa, previo dictamen de la Fiscal\u00eda de Instrucci\u00f3n de la Dra. Sonia Meza, ahora UFRAC, ante la denodada e insistente participaci\u00f3n de la Fiscal\u00eda de Estado en pos de la recuperaci\u00f3n de los bienes de la provincia, en los que los particulares debieron resignar sus intentos ante fallos que ordenan el desalojo y entrega de los bienes que son de la comunidad toda.&nbsp;<\/p>\n\n\n\n<p>\u201cLo que se concret\u00f3 en la fecha fue la entrega al titular del inmueble, luego de un prolongado litigio, donde en realidad la persona usurpadora hab\u00eda intentado vender el inmueble para posteriormente abandonarlo, siendo una manzana c\u00e9ntrica y privilegiada de la ciudad. Se trat\u00f3 de un trabajo articulado de manera tal de dejar bien en claro que los bienes usurpados del Estado son recuperados por su titular, y que usurparlos es un delito. Con \u00e9ste fallo que si bien es reparador, tambi\u00e9n lo es en su subtractum porque se trata no de una causa civil, sino en una penal donde el delito se configur\u00f3 y se repara mediante la devoluci\u00f3n a su real propietario\u201d, explic\u00f3 Ortega.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-12-18\/740214.jpg\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de una de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=927"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/927\/revisions"}],"predecessor-version":[{"id":1381,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/927\/revisions\/1381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/928"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}