{"id":687,"date":"2024-03-19T13:09:25","date_gmt":"2024-03-19T13:09:25","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=687"},"modified":"2024-03-19T13:09:25","modified_gmt":"2024-03-19T13:09:25","slug":"captores-de-gaby-la-soltaron-porque-se-les-habria-complicado","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2024\/03\/19\/captores-de-gaby-la-soltaron-porque-se-les-habria-complicado\/","title":{"rendered":"CAPTORES DE &#8220;GABY&#8221; LA SOLTARON PORQUE SE LES HABR\u00cdA &#8220;COMPLICADO&#8221;"},"content":{"rendered":"\n<p>Realizaron una videollamada usando el tel\u00e9fono de la v\u00edctima. Habr\u00eda intenciones de capturar a otras mujeres la misma noche que se la llevaron.<\/p>\n\n\n\n<p>La desaparici\u00f3n de Gabriela Fern\u00e1ndez, ocurrida el viernes por la noche cerca del barrio R\u00edo Paran\u00e1 de la capital correntina y su posterior aparici\u00f3n en el interior de la provincia de Chaco, a 180 kil\u00f3metros de distancia de su hogar, provoc\u00f3 en los \u00faltimos d\u00edas que se abra una investigaci\u00f3n exhaustiva. La mujer dijo que la hab\u00edan raptado varios sujetos en una camioneta gris, que le pusieron una tela en la cabeza y ven\u00edan hablando de otras mujeres m\u00e1s. Pero el plan se habr\u00eda desmoronado porque el rostro de &#8220;Gaby&#8221; apareci\u00f3 por todos lados y decidieron abandonarla. Ayer, una mujer describi\u00f3 un veh\u00edculo, con las mismas caracter\u00edsticas, que intent\u00f3 interceptarla por inmediaciones del barrio &#8220;La Chola&#8221;. La fiscal Graciela Fern\u00e1ndez Contarde dijo que &#8220;se est\u00e1n haciendo varias entrevistas&#8221;.<\/p>\n\n\n\n<p>Gabriela Fern\u00e1ndez declar\u00f3 ayer ante la fiscal Contarde y sostuvo que la raptaron varios sujetos en una camioneta gris con vidrios polarizados. La mujer hab\u00eda relatado que le colocaron una tela en la cabeza, como un trapo o una remera, que no le permit\u00eda ver el rostro de sus captores, y en esa situaci\u00f3n estuvo casi todo el tiempo.<\/p>\n\n\n\n<p>Los sujetos hablaban entre ellos con un acento que no ser\u00eda propio de la regi\u00f3n del nordeste, m\u00e1s bien parecida a la zona norte\u00f1a o puntana, seg\u00fan refiri\u00f3 la joven. Entre ellos hac\u00edan referencia a otras mujeres que al parecer ten\u00edan planeado captar, como si ya las tuvieran identificadas. Al menos dos mujeres m\u00e1s eran nombradas permanentemente por los sujetos.<\/p>\n\n\n\n<p>Varias horas despu\u00e9s de ser capturada y desde el tel\u00e9fono de Gabriela habr\u00edan realizado una videollamada al novio de la mujer y en cuyas im\u00e1genes se la podr\u00eda ver atada de pies y manos en una silla, como si hubiese sido golpeada, seg\u00fan relataron a diario \u00e9poca fuentes reservadas.<\/p>\n\n\n\n<p>Luego de ello, una vez m\u00e1s habr\u00edan usado el tel\u00e9fono de &#8220;Gaby&#8221;, pero esta vez para hacer un llamado a la cu\u00f1ada y mejor amiga. Esa llamada dur\u00f3 menos de cinco segundos y al parecer la joven habr\u00eda sido obligada a gritar &#8220;\u00a1auxilio, auxilio\u0085!&#8221; sin posibilidades de mandar alg\u00fan tipo de mensaje que direccione la investigaci\u00f3n de la Polic\u00eda.<\/p>\n\n\n\n<p>Este no fue un dato menor para los investigadores, ya que habitualmente en los raptos de los que se tenga conocimiento el celular de la v\u00edctima es lo primero que los secuestradores destruyen o hacen desaparecer, pero en esta oportunidad fue utilizado para contactar a los allegados de la v\u00edctima. Esto hubiera permitido a la Polic\u00eda, y a trav\u00e9s de geolocalizaci\u00f3n, trazar una ubicaci\u00f3n circunstancial de la v\u00edctima, pero no alcanzaron a llevar a cabo este procedimiento. El domingo a la ma\u00f1ana muy temprano, Gabriela apareci\u00f3 en la zona c\u00e9ntrica de la ciudad de S\u00e1enz Pe\u00f1a, en la provincia de Chaco, distante a unos 180 kil\u00f3metros del lugar donde hab\u00eda sido capturada.<\/p>\n\n\n\n<p>Vecinos de las calles 11, entre 12 y 14, dieron aviso a la Polic\u00eda chaque\u00f1a de la presencia de una joven que parec\u00eda desorientada y lastimada. Cuando los uniformados llegaron, pudieron constatar que efectivamente se trat\u00f3 de Gabriela Fern\u00e1ndez cuyo rostro hab\u00eda inundado de fotograf\u00edas las redes sociales en las \u00faltimas 48 horas.<\/p>\n\n\n\n<p>Ayer diario \u00e9poca intent\u00f3 obtener informaci\u00f3n con la fiscal del caso, Graciela Fern\u00e1ndez Contarde, quien fue cautelosa al indicar: &#8220;Por ahora no puedo adelantar nada, estamos investigando sobre el hecho. Se est\u00e1n llevando a cabo varias diligencias, entre ellas entrevistas&#8221;, sostuvo.<\/p>\n\n\n\n<p>Se estar\u00eda investigando una posible trata de personas, aunque por el momento la Justicia ordinaria no pidi\u00f3 colaboraci\u00f3n de las fuerzas federales en el caso. Otra mujer relat\u00f3 ayer a este medio que hab\u00eda tenido un incidente con otra camioneta de color gris oscuro con rayas negras. Fue cerca del barrio &#8220;La Chola&#8221;. No hay denuncia formal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizaron una videollamada usando el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=687"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/687\/revisions"}],"predecessor-version":[{"id":689,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/687\/revisions\/689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/688"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}