{"id":650,"date":"2023-12-15T14:20:59","date_gmt":"2023-12-15T14:20:59","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=650"},"modified":"2023-12-15T14:21:53","modified_gmt":"2023-12-15T14:21:53","slug":"corrientes-detenido-por-robarse-el-cartel-luminico-de-un-banco","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2023\/12\/15\/corrientes-detenido-por-robarse-el-cartel-luminico-de-un-banco\/","title":{"rendered":"CORRIENTES: DETENIDO POR ROBARSE EL CARTEL LUM\u00cdNICO DE UN BANCO"},"content":{"rendered":"\n<p>La inseguridad provoca situaciones que son absolutamente ins\u00f3litas. Es que los &#8220;due\u00f1os de lo ajeno&#8221; ya no tienen l\u00edmites para llevarse &#8220;lo que sea&#8221;. En las \u00faltimas horas, la Polic\u00eda detuvo a un sujeto que se rob\u00f3&#8230; el cartel lum\u00ednico de un banco. De no creer.<\/p>\n\n\n\n<p>Efectivos policiales del Destacamento San Marcos, se hallaban realizando recorridas por el barrio Las Tejas y en inmediaciones de las calles Chubut y Bonastre procedieron a la demora de un hombre de 42 a\u00f1os de edad.<\/p>\n\n\n\n<p><br>En su poder secuestraron un cartel lum\u00ednico de una entidad bancaria (Banco de Corrientes) y el cual estaba envuelto en una bolsa.<\/p>\n\n\n\n<p>El demorado y lo secuestrado, fue trasladado a la Comisar\u00eda 7\u00b0, donde se prosiguen con las diligencias y tramites del caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La inseguridad provoca situaciones que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=650"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/650\/revisions"}],"predecessor-version":[{"id":652,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/650\/revisions\/652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/654"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}