{"id":6182,"date":"2026-03-24T21:45:55","date_gmt":"2026-03-24T21:45:55","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=6182"},"modified":"2026-03-26T21:50:59","modified_gmt":"2026-03-26T21:50:59","slug":"martinez-quarta-por-el-desafectado-balerdi-y-se-queda-afuera-montiel","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2026\/03\/24\/martinez-quarta-por-el-desafectado-balerdi-y-se-queda-afuera-montiel\/","title":{"rendered":"MART\u00cdNEZ QUARTA POR EL DESAFECTADO BALERDI Y SE QUEDA AFUERA MONTIEL"},"content":{"rendered":"\n<p>Al defensor de River se le presenta una buena chance para demostrarle a Lionel Scaloni que puede jugar el Mundial<a href=\"https:\/\/api.whatsapp.com\/send?text=Mart%C3%ADnez%20Quarta%20por%20el%20desafectado%20Balerdi%20y%20se%20queda%20afuera%20Montiel%20-%20https:\/\/www.diarionorte.com\/325328-martinez-quarta-por-el-desafectado-balerdi-y-se-queda-afuera-montiel?utm_source=WhatsApp%26utm_medium=WhatsApp%26utm_campaign=WhatsApp%26utm_term=WhatsApp\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.diarionorte.com\/325328-martinez-quarta-por-el-desafectado-balerdi-y-se-queda-afuera-montiel#\"><\/a><a href=\"https:\/\/www.diarionorte.com\/325328-martinez-quarta-por-el-desafectado-balerdi-y-se-queda-afuera-montiel#\"><\/a><\/p>\n\n\n\n<p>Leonardo Balerdi, defensor de la Selecci\u00f3n argentina, fue desafectado de la convocatoria por una lesi\u00f3n y su lugar finalmente ser\u00e1 ocupado por Lucas Mart\u00ednez Quarta. Por otro lado, Gonzalo Montiel tambi\u00e9n es baja para los dos enfrentamientos.<a href=\"https:\/\/www.diarionorte.com\/325328-martinez-quarta-por-el-desafectado-balerdi-y-se-queda-afuera-montiel#\"><\/a><\/p>\n\n\n\n<p>La noticia fue confirmada cerca del mediod\u00eda a trav\u00e9s de las plataformas digitales de la Selecci\u00f3n argentina, que en esta doble fecha FIFA se enfrentar\u00e1 con sus pares de Mauritania y Zambia, en los que ser\u00e1n sus \u00faltimos partidos antes del Mundial de Estados Unidos, Qatar y M\u00e9xico 2026.<\/p>\n\n\n\n<p>&#8220;El futbolista Leonardo Balerdi queda desafectado de la n\u00f3mina por lesi\u00f3n. En su reemplazo, el cuerpo t\u00e9cnico convoca a Lucas Mart\u00ednez Quarta&#8221;, se detall\u00f3 en el comunicado.<\/p>\n\n\n\n<p>Si bien Balerdi gan\u00f3 mucho terreno en el \u00faltimo a\u00f1o en la Selecci\u00f3n argentina, su baja para estos encuentros podr\u00eda perjudicarlo gravemente de cara a la lista final de convocados para el Mundial 2026.<\/p>\n\n\n\n<p>Mart\u00ednez Quarta, por su parte, tendr\u00e1 una muy buena oportunidad para mostrarse en estos amistosos y convencer al director t\u00e9cnico de la Selecci\u00f3n argentina, Lionel Scaloni, de que lo convoque para el Mundial que empieza en solo ochenta d\u00edas.<\/p>\n\n\n\n<p>Finalmente, no se sabe si el lateral derecho del &#8220;Millonario&#8221; ser\u00e1 reemplazado o la convocatoria quedar\u00e1 con un jugador menos.<\/p>\n\n\n\n<p><strong>Inicio de la preparaci\u00f3n<\/strong><\/p>\n\n\n\n<p>La Selecci\u00f3n argentina tendr\u00e1 el calendario marcado durante esta semana, en la que jugar\u00e1 con el equipo de Mauritania en el marco de un amistoso internacional que ser\u00e1 el primero de los dos que tiene programado el conjunto nacional en la ante\u00faltima fecha FIFA previa al Mundial de Canad\u00e1, Estados Unidos y M\u00e9xico 2026.<\/p>\n\n\n\n<p>La actividad comenz\u00f3 ayer, d\u00eda en el que los representantes del campe\u00f3n del Mundo y bicampe\u00f3n de Am\u00e9rica iniciaron el arribo al pa\u00eds, ya que la mayor\u00eda de los convocados juegan en el f\u00fatbol europeo y algunos, entre los que se destaca el astro Lionel Messi, lo hacen en Norteam\u00e9rica.<\/p>\n\n\n\n<p>Las pr\u00e1cticas del seleccionado comandado por Lionel Scaloni, comenzar\u00e1n hoy y las mismas ser\u00e1n hasta el jueves 26, todas en horario vespertino en el predio de Ezeiza.<\/p>\n\n\n\n<p>Adem\u00e1s, el entrenador de 47 a\u00f1os dar\u00e1 una conferencia de prensa el jueves, mientras que el viernes ser\u00e1 el primer amistoso entre Argentina con Mauritania a las 20.15 en el estadio Alberto J. Armando, m\u00e1s conocido como &#8220;La Bombonera&#8221;.<\/p>\n\n\n\n<p>El segundo encuentro de la Selecci\u00f3n en la fecha FIFA ser\u00e1 frente a Zambia, otro rival africano que no accedi\u00f3 a la pr\u00f3xima Copa del Mundo y el mismo se llevar\u00e1 a cabo el pr\u00f3ximo martes 31 de marzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al defensor de River se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=6182"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6182\/revisions"}],"predecessor-version":[{"id":6184,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6182\/revisions\/6184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/6183"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=6182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=6182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=6182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}