{"id":6126,"date":"2026-03-20T20:51:47","date_gmt":"2026-03-20T20:51:47","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=6126"},"modified":"2026-03-26T20:54:01","modified_gmt":"2026-03-26T20:54:01","slug":"la-side-publico-documentos-desclasificados-de-la-decada-del-70","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2026\/03\/20\/la-side-publico-documentos-desclasificados-de-la-decada-del-70\/","title":{"rendered":"LA SIDE PUBLIC\u00d3 DOCUMENTOS DESCLASIFICADOS DE LA D\u00c9CADA DEL 70"},"content":{"rendered":"\n<p>Un paquete de 26 documentos con informes y memorandos ahora quedan a disposici\u00f3n de investigadores y el p\u00fablico general.<a href=\"https:\/\/api.whatsapp.com\/send?text=La%20SIDE%20public%C3%B3%20documentos%20desclasificados%20de%20la%20d%C3%A9cada%20del%2070%20-%20https:\/\/www.diarionorte.com\/325132-la-side-publico-documentos-desclasificados-de-la-decada-del-70?utm_source=WhatsApp%26utm_medium=WhatsApp%26utm_campaign=WhatsApp%26utm_term=WhatsApp\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.diarionorte.com\/325132-la-side-publico-documentos-desclasificados-de-la-decada-del-70#\"><\/a><a href=\"https:\/\/www.diarionorte.com\/325132-la-side-publico-documentos-desclasificados-de-la-decada-del-70#\"><\/a><\/p>\n\n\n\n<p>El gobierno nacional inici\u00f3 el proceso de desclasificaci\u00f3n de archivos de inteligencia correspondientes al per\u00edodo 1973-1983 y difundi\u00f3 el primer paquete de documentos oficiales. La medida fue implementada por la Secretar\u00eda de Inteligencia de Estado (SIDE) en cumplimiento de una disposici\u00f3n de Javier Milei.<a href=\"https:\/\/www.diarionorte.com\/325132-la-side-publico-documentos-desclasificados-de-la-decada-del-70#\"><\/a><\/p>\n\n\n\n<p>Se trata de 26 documentos que re\u00fanen 492 p\u00e1ginas, junto con una gu\u00eda explicativa para facilitar su lectura. El material incluye resoluciones, informes, memorandos, circulares y directivas producidas entre el 1 de enero de 1973 y el 10 de diciembre de 1983. La documentaci\u00f3n ya est\u00e1 disponible para consulta p\u00fablica a trav\u00e9s del sitio oficial del organismo y ser\u00e1 difundida tambi\u00e9n en sus redes sociales. Adem\u00e1s, el proceso contempla adem\u00e1s la conservaci\u00f3n y el posterior traspaso del material al Archivo General de la Naci\u00f3n<\/p>\n\n\n\n<p><strong>C\u00f3mo acceder<\/strong><\/p>\n\n\n\n<p>Los archivos fueron organizados en carpetas tem\u00e1ticas, de acuerdo con criterios de relevancia hist\u00f3rica e institucional. El objetivo es ordenar la informaci\u00f3n para su an\u00e1lisis por parte de investigadores, periodistas y ciudadanos interesados en el per\u00edodo.<\/p>\n\n\n\n<p>De esta manera, la SIDE elabor\u00f3 una &#8220;Gu\u00eda sobre la Desclasificaci\u00f3n de Documentos Hist\u00f3ricos&#8221; para acompa\u00f1ar la publicaci\u00f3n inicial. El documento busca aportar contexto y herramientas de lectura sobre el material difundido; as\u00ed la apertura de archivos previamente secretos apunta a mejorar el acceso a la informaci\u00f3n p\u00fablica. En ese sentido, la iniciativa se inscribe en una pol\u00edtica oficial orientada a reforzar el funcionamiento del Sistema de Inteligencia Nacional y su v\u00ednculo con la sociedad.<\/p>\n\n\n\n<p>Finalmente, desde la Secretar\u00eda expresaron que esperan que el material resulte \u00fatil para historiadores, comunicadores e investigadores. A su vez, se\u00f1alaron que con la difusi\u00f3n progresiva de archivos busca el acceso p\u00fablico a archivos de relevancia hist\u00f3rica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un paquete de 26 documentos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=6126"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6126\/revisions"}],"predecessor-version":[{"id":6128,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6126\/revisions\/6128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/6127"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=6126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=6126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=6126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}