{"id":6123,"date":"2026-03-20T20:51:01","date_gmt":"2026-03-20T20:51:01","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=6123"},"modified":"2026-03-26T20:54:04","modified_gmt":"2026-03-26T20:54:04","slug":"se-acerca-el-juicio-por-el-crimen-de-romina-karban","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2026\/03\/20\/se-acerca-el-juicio-por-el-crimen-de-romina-karban\/","title":{"rendered":"SE ACERCA EL JUICIO POR EL CRIMEN DE ROMINA KARBAN"},"content":{"rendered":"\n<p>Las audiencias preliminares del Juicio por Jurados por el homicidio de la joven ocurrido en el a\u00f1o\u00a0 2024 se pondr\u00e1n en marcha.<a href=\"https:\/\/api.whatsapp.com\/send?text=Se%20acerca%20el%20juicio%20por%20el%20crimen%20de%20Romina%20Karban%20-%20https:\/\/www.diarionorte.com\/325192-se-acerca-el-juicio-por-el-crimen-de-romina-karban?utm_source=WhatsApp%26utm_medium=WhatsApp%26utm_campaign=WhatsApp%26utm_term=WhatsApp\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.diarionorte.com\/325192-se-acerca-el-juicio-por-el-crimen-de-romina-karban#\"><\/a><a href=\"https:\/\/www.diarionorte.com\/325192-se-acerca-el-juicio-por-el-crimen-de-romina-karban#\"><\/a><\/p>\n\n\n\n<p>S\u00c1ENZ PE\u00d1A (Agencia). El pr\u00f3ximo 7 de abril en la C\u00e1mara Segunda en lo Criminal, a cargo de la jueza Rosana Glibota, comenzar\u00e1n las audiencias preliminares por el asesinato de Romina Karban. La joven de 30 a\u00f1os que fue ultimada de varios disparos en la cabeza el 8 de mayo de 2024.<a href=\"https:\/\/www.diarionorte.com\/325192-se-acerca-el-juicio-por-el-crimen-de-romina-karban#\"><\/a><\/p>\n\n\n\n<p>El cuerpo de la joven fue encontrado al d\u00eda siguiente en un campo de la zona rural conocida como Pampa Florida, ubicado a 12 kil\u00f3metros hacia el norte de esta ciudad, y por el hecho esta detenido el hermano, Renzo Karban como el supuesto asesino.<a href=\"https:\/\/www.diarionorte.com\/325192-se-acerca-el-juicio-por-el-crimen-de-romina-karban#\"><\/a><\/p>\n\n\n\n<p>A poco de cumplirse dos a\u00f1os del asesinato de la joven, un caso que conmocion\u00f3 a toda la ciudad, no solamente por el hecho en s\u00ed, tambi\u00e9n dejando un gran asombro porque el principal acusado del cruel asesinato habr\u00eda sido su mismo hermano Renzo, quien es el \u00fanico detenido por el crimen.<\/p>\n\n\n\n<p>Cabe recordar que la investigaci\u00f3n del asesinato de Romina Karban estuvo a cargo de la exfiscal Liliana Lupi, quien fue durante varios meses incluso tras la detenci\u00f3n del hermano, sindicado como el responsable de los disparos con una pistola 9 mil\u00edmetros, arma que nunca se lleg\u00f3 a encontrar, que el m\u00f3vil del crimen fue una herencia familiar, seg\u00fan hab\u00eda comentado la exfiscal en su momento.<\/p>\n\n\n\n<p>La investigaci\u00f3n tambi\u00e9n en un principio se centr\u00f3 en allanamientos, incluido el departamento donde conviv\u00eda con su pareja, Ariel Ojeda. Pero las hip\u00f3tesis y el hilo de la investigaci\u00f3n a cargo de la fiscal nunca se alej\u00f3 de lo que habr\u00eda sido una disputa familiar por una herencia del campo, que habr\u00eda dejado su padre fallecido, Daniel Karban.<\/p>\n\n\n\n<p>Al ser encontrado el cuerpo de la mujer, en la mencionada zona rural, en un sector de monte y a unos escasos metros la motocicleta en la que se movilizaba, llam\u00f3 la atenci\u00f3n de los investigadores que pudieron corroborar que pudo ir hasta ese lugar acordando un encuentro con otra persona conocida. Y que se dedujo, tras los meses de investigaci\u00f3n, que la persona con la que se vio Romina fue su mismo hermano, Renzo<a href=\"https:\/\/www.diarionorte.com\/325192-se-acerca-el-juicio-por-el-crimen-de-romina-karban#\"><\/a><\/p>\n\n\n\n<p>En lo que respecta al inicio de las audiencias preliminares que se dar\u00e1n previo al juicio por Jurado Popular, a cargo de la jueza t\u00e9cnica Rosana Glibota de la C\u00e1mara Segunda en lo Criminal, tendr\u00e1 como abogado del imputado al defensor oficial Mat\u00edas Jachesky y fiscal de C\u00e1mara a la doctora Mar\u00eda Rosa Osiska.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las audiencias preliminares del Juicio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6123","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=6123"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6123\/revisions"}],"predecessor-version":[{"id":6125,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/6123\/revisions\/6125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/6124"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=6123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=6123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=6123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}