{"id":5541,"date":"2026-02-07T11:17:32","date_gmt":"2026-02-07T11:17:32","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=5541"},"modified":"2026-02-10T11:22:09","modified_gmt":"2026-02-10T11:22:09","slug":"la-policia-investiga-extranas-mutilaciones-de-vacunos","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2026\/02\/07\/la-policia-investiga-extranas-mutilaciones-de-vacunos\/","title":{"rendered":"LA POLIC\u00cdA INVESTIGA EXTRA\u00d1AS MUTILACIONES DE VACUNOS"},"content":{"rendered":"\n<p>Productores ganaderos reportaron animales sin ojos ni lengua. La Divisi\u00f3n Rural enviar\u00e1 personal para constatar lo sucedido.<a href=\"https:\/\/api.whatsapp.com\/send?text=La%20Polic%C3%ADa%20investiga%20extra%C3%B1as%20mutilaciones%20de%20vacunos%20-%20https:\/\/www.diarionorte.com\/323328-la-policia-investiga-extranas-mutilaciones-de-vacunos?utm_source=WhatsApp%26utm_medium=WhatsApp%26utm_campaign=WhatsApp%26utm_term=WhatsApp\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.diarionorte.com\/323328-la-policia-investiga-extranas-mutilaciones-de-vacunos#\"><\/a><a href=\"https:\/\/www.diarionorte.com\/323328-la-policia-investiga-extranas-mutilaciones-de-vacunos#\"><\/a><\/p>\n\n\n\n<p>La calma de la zona rural de Colonia Popular se vio sacudida por un hecho inquietante que r\u00e1pidamente gener\u00f3 comentarios y especulaciones entre los productores ganaderos.<\/p>\n\n\n\n<p>En las \u00faltimas horas, comenzaron a circular im\u00e1genes de animales vacunos con extra\u00f1as mutilaciones: ausencia de ojos y lengua, un cuadro que despert\u00f3 preocupaci\u00f3n y curiosidad.<\/p>\n\n\n\n<p>El primer aviso se conoci\u00f3 alrededor de las 23 del martes, cuando un productor de Puerto Tirol comparti\u00f3 en el grupo de Whatsapp &#8220;Ganaderos&#8221; la fotograf\u00eda de un vacuno de pelaje colorado que presentaba esas anomal\u00edas.<\/p>\n\n\n\n<p>Minutos m\u00e1s tarde, otro productor difundi\u00f3 im\u00e1genes de un segundo animal con caracter\u00edsticas similares, aunque con diferencias en el pelaje. La noticia se propag\u00f3 r\u00e1pidamente entre los vecinos de la zona, quienes recordaron episodios anteriores vinculados a hechos similares.<\/p>\n\n\n\n<p>Algunos, incluso, no dudaron en asociar lo ocurrido con el famoso mito del &#8220;chupacabras&#8221;, un fen\u00f3meno que desde hace d\u00e9cadas alimenta relatos populares en distintas regiones.<\/p>\n\n\n\n<p>Los efectivos de la Divisi\u00f3n Rural Colonia Popular, dependiente de la Direcci\u00f3n General de Seguridad Rural y Ambiental, confirmaron que tomaron conocimiento del caso y que se contactaron telef\u00f3nicamente con los productores involucrados. Ambos manifestaron que no deseaban radicar una denuncia formal, aunque reconocieron su preocupaci\u00f3n por lo sucedido.<\/p>\n\n\n\n<p>Desde la Divisi\u00f3n Rural, se inform\u00f3 que durante la jornada se comisionar\u00e1 personal policial para verificar la situaci\u00f3n en el lugar y constatar de manera oficial lo ocurrido. Mientras tanto, en los corrillos de la zona, la conversaci\u00f3n gira entre la incredulidad, el temor y la fascinaci\u00f3n por un misterio que vuelve a instalarse en el imaginario popular chaque\u00f1o.<\/p>\n\n\n\n<p><strong>Entre mito y creencias<\/strong><\/p>\n\n\n\n<p>El &#8220;chupacabras&#8221; es una criatura legendaria que forma parte del folclore moderno en Am\u00e9rica Latina y otras regiones. Su nombre proviene de la idea de que ataca cabras y animales de campo para chuparles la sangre. Vacas, ovejas y otros animales dom\u00e9sticos fueros hallados muertos con heridas extra\u00f1as, los que conforman la variedad de ejemplares del m\u00edtico ejemplar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Productores ganaderos reportaron animales sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5542,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=5541"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5541\/revisions"}],"predecessor-version":[{"id":5543,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5541\/revisions\/5543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/5542"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=5541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=5541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=5541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}