{"id":5453,"date":"2026-02-01T13:30:11","date_gmt":"2026-02-01T13:30:11","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=5453"},"modified":"2026-02-02T13:03:21","modified_gmt":"2026-02-02T13:03:21","slug":"alan-buchholz-es-un-desafio-grande-pasar-de-categoria-y-no-desentonar","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2026\/02\/01\/alan-buchholz-es-un-desafio-grande-pasar-de-categoria-y-no-desentonar\/","title":{"rendered":"ALAN BUCHHOLZ: &#8220;ES UN DESAF\u00cdO GRANDE PASAR DE CATEGOR\u00cdA Y NO DESENTONAR&#8221;"},"content":{"rendered":"\n<p>Despu\u00e9s de ser uno de los protagonistas habituales de la Clase 2, el nacido en Gancedo ser\u00e1 el \u00fanico representante de la provincia en la Clase 3.\u00a0<a href=\"https:\/\/api.whatsapp.com\/send?text=Alan%20Buchholz:%20%22Es%20un%20desaf%C3%ADo%20grande%20pasar%20de%20categor%C3%ADa%20y%20no%20desentonar%22%20-%20https:\/\/www.diarionorte.com\/322980-alan-buchholz-es-un-desafio-grande-pasar-de-categoria-y-no-desentonar?utm_source=WhatsApp%26utm_medium=WhatsApp%26utm_campaign=WhatsApp%26utm_term=WhatsApp\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.diarionorte.com\/322980-alan-buchholz-es-un-desafio-grande-pasar-de-categoria-y-no-desentonar#\"><\/a><a href=\"https:\/\/www.diarionorte.com\/322980-alan-buchholz-es-un-desafio-grande-pasar-de-categoria-y-no-desentonar#\"><\/a><\/p>\n\n\n\n<p>El Turismo Pista comenzar\u00e1 este fin de semana su temporada 2026 y el aut\u00f3dromo &#8220;Roberto Mouras&#8221; de La Plata, en la provincia de Buenos Aires, es el escenario elegido para la primera carrera del a\u00f1o que contar\u00e1 con la presencia de tres pilotos chaque\u00f1os. El saenzpe\u00f1ense Rolando L\u00f3pez y el resistenciano Agust\u00edn Gajate ser\u00e1n de la partida entre los 43 inscriptos en la Clase 2, mientras que el de Gancedo, Alan Buchholz, ser\u00e1 el \u00fanico que tendr\u00e1 acci\u00f3n en la Clase 3. En total, ser\u00e1n 45 pilotos en la Clase 1 (41 con Fiat Uno y cuatro con Chevrolet Corsa), 43 en la Clase 2 y 45 en la Clase 3.<\/p>\n\n\n\n<p>Y fue el propio Alan Buchholz, quien, en di\u00e1logo con NORTE, palpit\u00f3 que lo que ser\u00e1 el inicio de esta temporada. &#8220;Se acerca este fin de semana. Es la primera fecha del campeonato y muy contento de dar un salto en mi carrera deportiva. Despu\u00e9s de tres a\u00f1os de ser parte de la Clase 2, pegamos el salto a la Clase 3, que es la divisional mayor que tiene la categor\u00eda. Muy contentos de esta oportunidad&#8221;, dijo el piloto nacido en Gancedo.<\/p>\n\n\n\n<p>Cabe destacar que despu\u00e9s de ser uno de los protagonistas habituales de la Clase 2, Buchholz pegar\u00e1 el salto a la divisional mayor con un Volkswagen Gol Trend que supo utilizar Ignacio Rodr\u00edguez y mantendr\u00e1 la atenci\u00f3n del Bailone Racing Team, mientras que la motorizaci\u00f3n tambi\u00e9n continuar\u00e1 en manos de Leandro Lamuedra, sosteniendo as\u00ed el conjunto con el que el chaque\u00f1o fue competitivo en la divisional intermedia.<\/p>\n\n\n\n<p>Y se explay\u00f3: &#8220;Sabemos que es un desaf\u00edo bastante grande pasar de categor\u00eda y no desentonar. Comenzamos con buenas expectativas, sabemos del potencial que tiene el conjunto, seguimos trabajando con el mismo motorista y chasis que con el que lo vinimos haciendo en los 3 a\u00f1os que estuvimos en la Clase 2&#8221;.&nbsp;<\/p>\n\n\n\n<p>Alan Buchholz fue claro: &#8220;Todo es un conjunto que conozco muy bien y que s\u00e9 de las capacidades. Conf\u00edo en que en que trabajando mucho vamos a poder pelear tambi\u00e9n dentro de la Clase 3, como lo hicimos en la Clase2. Arrancamos con buenas expectativas, pero sabemos que nos llevar\u00e1 tiempo adaptarnos&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LAS DIFERENCIAS DE CATEGOR\u00cdA&nbsp;<\/h2>\n\n\n\n<p>&#8220;Cambia mucho el auto por ah\u00ed en cuanto potencia, caja, freno, cubiertas. Es bastante distinto a lo que ven\u00eda acostumbrado, as\u00ed que vamos a tener que estar tranquilos, ser pacientes, y saber que nos puede llevar tiempo adaptarnos y estar de vuelta en la pelea&#8221;, dijo Alan Buchholz.&nbsp;<\/p>\n\n\n\n<p>Y en cuanto al objetivo se\u00f1al\u00f3: &#8220;Es una nueva experiencia para m\u00ed, es una nueva categor\u00eda, as\u00ed que nada lo tomo con bastante tranquilidad. No me pongo objetivos tan optimistas como fue el a\u00f1o pasado dentro de la Clase 2, que sab\u00edamos que nuestro objetivo era pelear por el campeonato. Lo importante ser\u00e1 saber c\u00f3mo responde el auto en las primeras fechas y de ah\u00ed ver donde estamos parados&#8221;.&nbsp;<\/p>\n\n\n\n<p>Alan Buchholz se explay\u00f3: &#8220;Es una categor\u00eda s\u00faper competitiva, con muchos autos y muy buenos pilotos, equipos de muy buen nivel, as\u00ed que sabemos que no va ser\u00e1 nada f\u00e1cil, pero entendiendo que con el trabajo del equipo y m\u00edo, y algo de tiempo, vamos a poder ser protagonistas&#8221;. &#8220;A largo plazo s\u00ed, obviamente, el objetivo es ser candidatos y pelear campeonatos, pero hoy en d\u00eda creo que no s\u00e9 si vamos a estar para eso. Las expectativas igualmente son buenas y creo que podemos pelear por estar dentro de los 15&#8221;, sentenci\u00f3.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">EL PRESUPUESTO Y LA COMPLICACIONES&nbsp;<\/h2>\n\n\n\n<p>&#8220;El tema de la econom\u00eda es un tema bastante sensible, bastante dif\u00edcil en lo que es el automovilismo. Nadie escapa por ah\u00ed del contexto y de la de la situaci\u00f3n tan dif\u00edcil que est\u00e1 atravesando por ah\u00ed el pa\u00eds. Es dif\u00edcil juntar el presupuesto para para estar presente en todas las fechas, y por nuestra parte m\u00e1s todav\u00eda que este a\u00f1o pegamos el salto, y el estar en una categor\u00eda un poco m\u00e1s grande, tambi\u00e9n conlleva que los n\u00fameros se inflen un poco m\u00e1s y sea por ah\u00ed m\u00e1s dif\u00edcil juntar tambi\u00e9n el presupuesto&#8221;, explic\u00f3 Alan Buchholz.<\/p>\n\n\n\n<p>Y a\u00f1adi\u00f3: &#8220;En mi caso tengo a mi viejo con el cual compartimos much\u00edsimo esta pasi\u00f3n y la verdad que \u00e9l se mueve much\u00edsimo para para poder juntar el apoyo necesario y poder estar presentes en todas las fechas. Obviamente poniendo de nuestra parte y juntando la mayor cantidad de empresas que nos apoyen en nuestra carrera deportiva, as\u00ed que agradecido con todas las empresas que conf\u00edan en nosotros y nos dan una mano realmente grande para para poder estar presentes&#8221;. &#8220;En cuanto a la provincia estamos intentando tramitar tambi\u00e9n la Ley de Sponsorizaci\u00f3n, que es una ayuda muy grande para a los deportistas. Siempre trabajando muy fuerte para para poder juntar el presupuesto&#8221;, explic\u00f3 el nacido en Gancedo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SUS SUE\u00d1OS DENTRO DEL DEPORTE TUERCA&nbsp;<\/h2>\n\n\n\n<p>&#8220;Dentro del automovilismo, obviamente, uno siempre busca m\u00e1s. El desaf\u00edo o el objetivo que tengo por cumplir es llegar a la categor\u00eda m\u00e1s alta de este tipo de autos, que son los Clase 3 del Turismo Nacional. Obviamente es un objetivo a largo plazo y donde que hay que ir escalando paso a paso e ir sumando experiencia. En este caso, en la Clase 3 del Turismo Pista, todav\u00eda nos toca un largo camino por delante, pero obviamente el objetivo, el sue\u00f1o es competir en la Clase 3 del Turismo Nacional&#8221;, cerr\u00f3 Alan Buchholz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de ser uno de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5454,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5453","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=5453"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5453\/revisions"}],"predecessor-version":[{"id":5455,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5453\/revisions\/5455"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/5454"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=5453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=5453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=5453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}