{"id":5388,"date":"2026-01-27T11:47:27","date_gmt":"2026-01-27T11:47:27","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=5388"},"modified":"2026-01-29T11:51:20","modified_gmt":"2026-01-29T11:51:20","slug":"el-oficialismo-llevara-la-baja-de-la-edad-de-imputabilidad-a-sesiones-extraordinarias","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2026\/01\/27\/el-oficialismo-llevara-la-baja-de-la-edad-de-imputabilidad-a-sesiones-extraordinarias\/","title":{"rendered":"EL OFICIALISMO LLEVAR\u00c1 LA BAJA DE LA EDAD DE IMPUTABILIDAD A SESIONES EXTRAORDINARIAS"},"content":{"rendered":"\n<p>El proyecto se debatir\u00e1 entre el 2 y el 27 de febrero tras una decisi\u00f3n de la mesa pol\u00edtica en la Casa Rosada.<a href=\"https:\/\/api.whatsapp.com\/send?text=El%20oficialismo%20llevar%C3%A1%20la%20baja%20de%20la%20edad%20de%20imputabilidad%20a%20sesiones%20extraordinarias%20-%20https:\/\/www.diarionorte.com\/322859-el-oficialismo-llevara-la-baja-de-la-edad-de-imputabilidad-a-sesiones-extraordinarias?utm_source=WhatsApp%26utm_medium=WhatsApp%26utm_campaign=WhatsApp%26utm_term=WhatsApp\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.diarionorte.com\/322859-el-oficialismo-llevara-la-baja-de-la-edad-de-imputabilidad-a-sesiones-extraordinarias#\"><\/a><a href=\"https:\/\/www.diarionorte.com\/322859-el-oficialismo-llevara-la-baja-de-la-edad-de-imputabilidad-a-sesiones-extraordinarias#\"><\/a><\/p>\n\n\n\n<p>A una semana del inicio de las sesiones extraordinarias, el gobierno nacional anunci\u00f3 que el proyecto de baja de la edad de imputabilidad ser\u00e1 parte del temario legislativo. A trav\u00e9s de la red social X, el jefe de Gabinete, Manuel Adorni, anticip\u00f3 que luego de encabezar una reuni\u00f3n de la mesa pol\u00edtica decidieron incluir la Ley Penal Juvenil en el debate de febrero.<\/p>\n\n\n\n<p>&#8220;Reunidos en la Casa Rosada desde temprano. La &#8220;Ley Penal Juvenil&#8221; tambi\u00e9n formar\u00e1 parte del temario de las sesiones extraordinarias. Fin&#8221;, public\u00f3 el funcionario. En la cumbre participaron la secretaria general de la Presidencia, Karina Milei; los ministros Diego Santilli y Luis Caputo; el titular de la C\u00e1mara de Diputados, Mart\u00edn Menem; la ministra Patricia Bullrich; el asesor Santiago Caputo y el secretario de Asuntos Estrat\u00e9gicos, Ignacio Devitt.<\/p>\n\n\n\n<p>El diputado de LLA , Luis Petri, public\u00f3 en su cuenta de X &#8220;\u00a1bajar la edad de imputabilidad es urgente y necesario! \u00bfCu\u00e1ntas nuevas v\u00edctimas vamos a esperar para reformar una ley que demuestra su fracaso cada vez que un hecho violento deja a una familia destrozada en manos de un peligroso delincuente que mata a sangre fr\u00eda?&#8221;. Bullrich por su parte destac\u00f3 &#8220;la sociedad necesita justicia y prevenir nuevas v\u00edctimas. No m\u00e1s excusas ni dilaciones&#8221;.<\/p>\n\n\n\n<p><strong>Claves del nuevo R\u00e9gimen Penal Juvenil<\/strong><\/p>\n\n\n\n<p>El plenario de las comisiones de Legislaci\u00f3n Penal, Presupuesto, Justicia y Familias de la C\u00e1mara de Diputados trabaj\u00f3 durante varios meses sobre 12 proyectos que propon\u00edan establecer la edad de imputabilidad entre los 12 y los 16 a\u00f1os.<\/p>\n\n\n\n<p>Finalmente, el consenso alcanzado establece que el r\u00e9gimen penal cambie de los 16 a los 14 a\u00f1os. El proyecto contempla penas m\u00e1ximas de hasta 15 a\u00f1os de prisi\u00f3n y sanciones alternativas para condenas menores a 10 a\u00f1os, tales como servicios comunitarios, prohibici\u00f3n de conducci\u00f3n y reparaciones econ\u00f3micas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto se debatir\u00e1 entre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5388","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=5388"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5388\/revisions"}],"predecessor-version":[{"id":5390,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5388\/revisions\/5390"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/5389"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=5388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=5388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=5388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}