{"id":5330,"date":"2026-01-22T10:26:47","date_gmt":"2026-01-22T10:26:47","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=5330"},"modified":"2026-01-26T10:27:30","modified_gmt":"2026-01-26T10:27:30","slug":"villa-angela-se-prepara-para-la-gran-fiesta-del-carnaval-2026","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2026\/01\/22\/villa-angela-se-prepara-para-la-gran-fiesta-del-carnaval-2026\/","title":{"rendered":"VILLA \u00c1NGELA SE PREPARA PARA LA GRAN FIESTA DEL CARNAVAL 2026"},"content":{"rendered":"\n<p>La secretaria de Cultura del municipio, Alejandra B\u00fchler, confirm\u00f3 el orden de salida de las comparsas con la presencia de los dirigentes de las distintas agrupaciones<a href=\"https:\/\/www.diarionorte.com\/322630-villa-angela-se-prepara-para-la-gran-fiesta-del-carnaval-2026#\"><\/a><\/p>\n\n\n\n<p>VILLA \u00c1NGELA (Agencia). La organizaci\u00f3n de los carnavales genera siempre gran expectativa, especialmente con la confirmaci\u00f3n de las comparsas participantes y del sorteo donde se define el orden de salidas de las distintas agrupaciones, que brillar\u00e1n en la fiesta del rey Momo.<\/p>\n\n\n\n<p>La secretaria de Cultura, Turismo y Deportes, Alejandra B\u00fchler, confirm\u00f3 el orden de salida de las comparsas tras el sorteo oficial realizado en la Casa del Bicentenario con la presencia de los dirigentes de todas las comparsas de la ciudad. La confirmaci\u00f3n se da en el marco de la organizaci\u00f3n de los Carnavales 2026, que contar\u00e1n con comparsas mayores e infantiles y jurados provenientes de distintas provincias.<\/p>\n\n\n\n<p>&#8220;Realizamos el sorteo del orden de comparsas, festejando tambi\u00e9n este evento, este gran festival carnavalesco que tenemos aqu\u00ed en Villa \u00c1ngela, por una decisi\u00f3n del Ejecutivo del intendente Adalberto Papp, de apostar a esta gran fiesta que son los carnavales villangelenses&#8221;, sostuvo.<\/p>\n\n\n\n<p><strong>Valor cultural y social del evento<\/strong><\/p>\n\n\n\n<p>&#8220;La verdad es que se destaca no solo por su brillo, por la cantidad de bailarines, por sus escolas, sino tambi\u00e9n por los semilleros que son las comparsas, las tres comparsas infantiles que acompa\u00f1an a las comparsas mayores, eso es algo \u00fanico aqu\u00ed en el Chaco y es digno de destacar, como tambi\u00e9n esta decisi\u00f3n del ingeniero de apoyar a los carnavales, ya que es un motor para la econom\u00eda local, es un evento donde todo el mundo tiene trabajo&#8221;, manifest\u00f3 la funcionaria.<\/p>\n\n\n\n<p>Asimismo, B\u00fchler remarc\u00f3 el impacto econ\u00f3mico y social de la fiesta. &#8220;Todo el mundo puede acceder a un espacio en el cors\u00f3dromo para vender, ya sea comida, las nieves; las instituciones educativas participan con la venta de entradas, que tambi\u00e9n tienen una comisi\u00f3n, recaudan algo de plata, como as\u00ed algunos clubes y asociaciones para poder solventar los gastos que se enfrentan en 2026, como todos los a\u00f1os, as\u00ed que es digno de destacar esta decisi\u00f3n y tambi\u00e9n nosotros ser parte de la log\u00edstica y de estar en permanente colaboraci\u00f3n para que salga lo mejor posible&#8221;.<\/p>\n\n\n\n<p>&#8220;Quiero agradecer a la comisi\u00f3n y tambi\u00e9n a Loli Garc\u00eda, que est\u00e1 poniendo todo su empe\u00f1o con todo su equipo, trabajando y acompa\u00f1ando a la comisi\u00f3n organizadora. La verdad es que es un gusto estar en estas organizaciones donde somos noticia regional y nacional, me animar\u00eda a decirlo&#8221;, dijo.<\/p>\n\n\n\n<p><strong>Orden de salida<\/strong><\/p>\n\n\n\n<p>Respecto al resultado del sorteo, B\u00fchler detall\u00f3: &#8220;Se hizo el sorteo de salida de las tres primeras noches y la \u00faltima noche. En la primera noche abre la comparsa Ar\u00e1 Sun\u00fa, en segundo lugar est\u00e1 la comparsa Hawaianas y en tercer lugar Bah\u00eda, y en el mismo orden las comparsas infantiles&#8221;. &#8220;La segunda noche abre Bah\u00eda, luego Ar\u00e1 Sun\u00fa y cierra Hawaianas.<\/p>\n\n\n\n<p>La tercera noche abre Hawaianas, en segundo lugar sale Bah\u00eda y cierra Ar\u00e1 Sun\u00fa. Y la \u00faltima noche da inicio Hawaianas, en segundo lugar sale Ar\u00e1 Sun\u00fa y en tercer lugar Bah\u00eda, y en el mismo orden salen los infantiles, as\u00ed que esperemos con ansias la gran fiesta de Villa \u00c1ngela, que son los carnavales&#8221;, coment\u00f3. Finalmente, la secretaria se refiri\u00f3 a la organizaci\u00f3n general y al jurado. &#8220;Los jurados fueron elegidos por la comisi\u00f3n de cada una de las comparsas, acompa\u00f1ados por la comisi\u00f3n organizadora, as\u00ed que vienen jurados de Santa Fe, Buenos Aires y Corrientes&#8221;, dijo.<\/p>\n\n\n\n<p>&#8220;Todo est\u00e1 bien organizado, a pesar de que tuvimos algunos inconvenientes con la aprobaci\u00f3n de presupuesto y otras cuestiones, pero aun as\u00ed est\u00e1 todo muy bien. Como lo explicaba Jessica L\u00f3pez, la presidenta de la Unicomp la venta de entradas est\u00e1 a cargo de las instituciones educativas y tambi\u00e9n estar\u00e1 la comisi\u00f3n en el cors\u00f3dromo a partir de las 20; nosotros continuamos colaborando con la log\u00edstica y en lo que haga falta&#8221;, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La secretaria de Cultura del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=5330"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5330\/revisions"}],"predecessor-version":[{"id":5332,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5330\/revisions\/5332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/5331"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=5330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=5330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=5330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}