{"id":5142,"date":"2026-01-09T17:15:28","date_gmt":"2026-01-09T17:15:28","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=5142"},"modified":"2026-01-09T17:15:28","modified_gmt":"2026-01-09T17:15:28","slug":"el-banco-central-devolvio-al-tesoro-de-ee-uu-los-fondos-del-swap","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2026\/01\/09\/el-banco-central-devolvio-al-tesoro-de-ee-uu-los-fondos-del-swap\/","title":{"rendered":"EL BANCO CENTRAL DEVOLVI\u00d3 AL TESORO DE EE.UU. LOS FONDOS DEL SWAP"},"content":{"rendered":"\n<p>La autoridad monetaria lo inform\u00f3 en un comunicado. El secretario del Tesoro norteamericano, Scott Bessent, lo celebr\u00f3 como un signo de estabilizaci\u00f3n para la Argentina. El Gobierno hab\u00eda tomado US$2500 millones antes de las elecciones. La l\u00ednea sigue vigente.<\/p>\n\n\n\n<p>El Banco Central (BCRA) comunic\u00f3 que en diciembre devolvi\u00f3 los US$2500 millones que le hab\u00eda prestado Estados Unidos mediante el swap de monedas antes de las elecciones legislativas de octubre. El secretario del Tesoro, Scott Bessent, dijo que su pa\u00eds tuvo grandes ganancias con esta operaci\u00f3n y que contin\u00faa apoyando la gesti\u00f3n de Javier Milei.<\/p>\n\n\n\n<p>&nbsp;&#8220;El Banco Central de la Rep\u00fablica Argentina (BCRA) comunica que en diciembre de 2025 cancel\u00f3 las operaciones realizadas durante el cuarto trimestre de 2025 con el Departamento del Tesoro de los Estados Unidos, bajo el acuerdo de estabilizaci\u00f3n cambiaria por US$20.000 millones anunciado el 20 de octubre de 2025\u2033, inform\u00f3 la autoridad monetaria.<\/p>\n\n\n\n<p>&#8220;Ese acuerdo de estabilizaci\u00f3n cambiaria establece los t\u00e9rminos y condiciones para la realizaci\u00f3n de operaciones bilaterales de swap de monedas entre ambas partes&#8221;, complet\u00f3. Fuentes del Gobierno aclararon que, si bien la Argentina cancel\u00f3 el monto utilizado, el acuerdo de intercambio de monedas contin\u00faa vigente.<\/p>\n\n\n\n<p>La novedad lleg\u00f3 el mismo d\u00eda en el que el Gobierno logr\u00f3&nbsp;<strong>cancelar los vencimientos<\/strong>&nbsp;de bonos por m\u00e1s de&nbsp;<strong>US$4200 millones<\/strong>&nbsp;con fondos obtenidos mediante&nbsp;<strong>privatizaciones, compras de d\u00f3lares<\/strong>&nbsp;en el mercado y un&nbsp;<strong>pr\u00e9stamo de bancos internacionales<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El gobierno de EE.UU. reiter\u00f3 su apoyo a la Argentina<\/h2>\n\n\n\n<p>El secretario del Tesoro de EE.UU.,&nbsp;<strong>Scott Bessent<\/strong>, tambi\u00e9n anunci\u00f3 la cancelaci\u00f3n del tramo utilizado del swap. &#8220;Me complace anunciar que, como reflejo de su fortalecida posici\u00f3n financiera, Argentina ha reembolsado r\u00e1pida y completamente su limitada disposici\u00f3n del swap con Estados Unidos, de modo que el Fondo de Estabilizaci\u00f3n Cambiaria (FEC) actualmente no tiene pesos&#8221;, escribi\u00f3 en su cuenta de X.<\/p>\n\n\n\n<p>Y justific\u00f3: &#8220;Estabilizar a un fuerte aliado estadounidense, y generar decenas de millones en ganancias para los estadounidenses, es un gran logro de la iniciativa \u2018Am\u00e9rica Primero\u2019. Fijar el rumbo para Am\u00e9rica Latina, con una Argentina fuerte y estable que contribuya a consolidar un hemisferio occidental pr\u00f3spero, es sin duda lo mejor para nosotros&#8221;.<\/p>\n\n\n\n<p>El funcionario de Donald Trump asegur\u00f3 que el Fondo de Estabilizaci\u00f3n Cambiaria se us\u00f3 exactamente para lo que fue creado: estabilizar a la Argentina en un momento de crisis, con una presi\u00f3n aguda, a corto plazo y urgente de iliquidez sobre el tipo de cambio y la estabilidad financiera.<\/p>\n\n\n\n<p>&#8220;La comunidad internacional, incluido el FMI a trav\u00e9s de su amplio programa existente, se ha unido y sigue apoyando firmemente a Argentina, sus reformas actuales y su prudente estrategia fiscal. Pero solo Estados Unidos pudo actuar con la rapidez con la que lo hicimos en octubre para preservar la estabilidad del mercado y del tipo de cambio&#8221;, resalt\u00f3 Bessent.<\/p>\n\n\n\n<p>En la misma l\u00ednea, el secretario del Tesoro reiter\u00f3 que el Fondo nunca perdi\u00f3 dinero por las operaciones. &#8220;Nuestra naci\u00f3n recibi\u00f3 el reembolso completo, generando decenas de millones de d\u00f3lares en ganancias para el contribuyente estadounidense&#8221;, asegur\u00f3.<\/p>\n\n\n\n<p>Los t\u00e9rminos de la operaci\u00f3n son confidenciales y las cifras solamente se pueden conocer cuando el BCRA y el Tesoro de EE.UU. publican sus estad\u00edsticas oficiales. Fue as\u00ed como se devel\u00f3 que el tramo activado del swap antes de las elecciones legislativas lleg\u00f3 a los US$2500 millones.<\/p>\n\n\n\n<p>Finalmente, Bessent resalt\u00f3 que, tras la estabilizaci\u00f3n, los mercados de deuda ya est\u00e1n resolviendo las necesidades financieras de la Argentina. &#8220;El presidente Milei y el ministro de Finanzas, Luis Caputo, est\u00e1n generando un impulso positivo, y anticipamos que continuar\u00e1n progresando. Esperamos continuar con nuestro entusiasta apoyo al presidente Milei y a la Argentina&#8221;, cerr\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La autoridad monetaria lo inform\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5143,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=5142"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5142\/revisions"}],"predecessor-version":[{"id":5144,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/5142\/revisions\/5144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/5143"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=5142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=5142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=5142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}