{"id":4901,"date":"2025-12-23T01:14:48","date_gmt":"2025-12-23T01:14:48","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=4901"},"modified":"2025-12-29T21:16:33","modified_gmt":"2025-12-29T21:16:33","slug":"por-que-uruguay-no-celebra-oficialmente-la-navidad","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2025\/12\/23\/por-que-uruguay-no-celebra-oficialmente-la-navidad\/","title":{"rendered":"Por qu\u00e9 Uruguay no celebra oficialmente la Navidad"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Aunque la fecha se vive en familia como en el resto del mundo, el pa\u00eds vecino mantiene una postura laica y la reconoce en el calendario como D\u00eda de la Familia.<\/h5>\n\n\n\n<p><strong>Uruguay<\/strong>\u00a0ocupa un lugar singular dentro de Am\u00e9rica Latina por una particularidad que suele llamar la atenci\u00f3n tanto de turistas como de vecinos de la regi\u00f3n:\u00a0<strong>es el \u00fanico pa\u00eds que no reconoce oficialmente la Navidad como feriado bajo ese nombre.\u00a0<\/strong>Aunque cada 25 de diciembre miles de familias uruguayas se re\u00fanen, brindan y mantienen vivas las tradiciones navide\u00f1as, en los papeles del Estado\u00a0<strong>la fecha figura con otra denominaci\u00f3n<\/strong>, una decisi\u00f3n que responde a una historia marcada por la defensa del laicismo.<\/p>\n\n\n\n<p>En el&nbsp;<strong>calendario oficial<\/strong>,&nbsp;el 25 de diciembre aparece como&nbsp;<strong>\u201cD\u00eda de la Familia\u201d<\/strong>, un feriado no laborable que contrasta con el uso cotidiano y con lo que sucede en gran parte del mundo occidental. La diferencia<strong>&nbsp;no implica la prohibici\u00f3n de festejar ni un rechazo cultural<\/strong>&nbsp;a la Navidad, sino una postura institucional que evita referencias religiosas en las fechas oficiales, incluso en aquellas de fuerte arraigo popular.<\/p>\n\n\n\n<p>El origen de este cambio&nbsp;<strong>se remonta a comienzos del siglo XX<\/strong>, cuando Uruguay atraves\u00f3 un profundo proceso de<strong>&nbsp;reformas pol\u00edticas y sociales<\/strong>. En ese contexto, el pa\u00eds avanz\u00f3 de manera decidida hacia la separaci\u00f3n entre el Estado y la Iglesia, con el objetivo de consolidar un modelo laico. Esta l\u00ednea fue una de las banderas centrales del entonces presidente Jos\u00e9 Batlle y Ord\u00f3\u00f1ez, cuya gesti\u00f3n dej\u00f3 una huella duradera en la organizaci\u00f3n institucional del pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"498\" src=\"https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/12\/image-171.png\" alt=\"\" class=\"wp-image-4903\" srcset=\"https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/12\/image-171.png 900w, https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/12\/image-171-300x166.png 300w, https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/12\/image-171-768x425.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p><strong>La modificaci\u00f3n qued\u00f3 formalizada en 1919<\/strong>, cuando una ley redefini\u00f3 los feriados nacionales y elimin\u00f3 las denominaciones religiosas del calendario oficial.&nbsp;De ese modo, el 25 de diciembre&nbsp;<strong>dej\u00f3 de figurar como Navidad<\/strong>&nbsp;y pas\u00f3 a llamarse D\u00eda de la Familia. La misma l\u00f3gica se aplic\u00f3 a otras fechas tradicionales: el 6 de enero, por ejemplo,&nbsp;<strong>perdi\u00f3 su referencia a los Reyes Magos y fue rebautizado como D\u00eda de los Ni\u00f1os<\/strong>.<\/p>\n\n\n\n<p>Desde entonces, la Navidad sigue existiendo en Uruguay en el plano social, cultural y familiar, pero sin reconocimiento religioso ni nombre oficial por parte del Estado. Las reuniones, los brindis y los \u00e1rboles decorados conviven con una estructura institucional que mantiene una distancia clara respecto de las celebraciones confesionales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque la fecha se vive [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=4901"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4901\/revisions"}],"predecessor-version":[{"id":4904,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4901\/revisions\/4904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/4902"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=4901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=4901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=4901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}