{"id":4764,"date":"2025-12-15T22:58:37","date_gmt":"2025-12-15T22:58:37","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=4764"},"modified":"2025-12-29T21:11:50","modified_gmt":"2025-12-29T21:11:50","slug":"bullrich-fijo-un-plazo-para-sancionar-la-reforma-laboral-antes-de-fin-de-ano","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2025\/12\/15\/bullrich-fijo-un-plazo-para-sancionar-la-reforma-laboral-antes-de-fin-de-ano\/","title":{"rendered":"Bullrich fij\u00f3 un plazo para sancionar la reforma laboral: &#8220;Antes de fin de a\u00f1o&#8221;"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">La presidenta del bloque de senadores de la Libertad Avanza habl\u00f3 sobre las obras sociales, la informalidad laboral y la &#8220;cuota solidaria&#8221; de los sindicatos.<\/h5>\n\n\n\n<p>La presidenta del bloque de senadores de la Libertad Avanza (LLA), Patricia Bullrich, asegur\u00f3 este domingo por la noche que buscar\u00e1 sancionar la reforma laboral &#8220;antes de fin de a\u00f1o&#8221;. En paralelo, revel\u00f3 que su bloque est\u00e1 avanzando en conversaciones con varios bloques no kirchneristas.<\/p>\n\n\n\n<p>En declaraciones con LN+, la exministra de Seguridad inform\u00f3: &#8220;Tengo la decisi\u00f3n de llevar adelante esta ley, y con todo el bloque de la LLA estamos hablando con otras bancadas. Los kirchneristas ya dijeron que no, as\u00ed que no tenemos mucho que hablar con ellos, pero s\u00ed con otros&#8221;.<\/p>\n\n\n\n<p>Asimismo, subray\u00f3 que se trata de &#8220;una ley que se ha discutido mucho, ya hace 20 a\u00f1os que hablamos de leyes que hay que cambiar, y en este caso el sistema laboral ha cambiado en el mundo y tiene que cambiar tambi\u00e9n en la Argentina&#8221;.<\/p>\n\n\n\n<p>Desestim\u00f3 tambi\u00e9n que la norma proyectada cause desfinanciamiento de las obras sociales sindicales o de las ANSES. &#8220;La plata para las obras sociales va a crecer, porque si se blanquea el 43% (de trabajadores) que est\u00e1 en la informalidad, cada uno que blanquea va a aportar a la obra social que le corresponde, y entonces van a tener m\u00e1s dinero, no menos&#8221;, opin\u00f3.<\/p>\n\n\n\n<p>Agreg\u00f3 que &#8220;hay un 43% que est\u00e1 en negro y un 30% en \u2018gris\u2019, y con esta ley bajamos las cargas para que m\u00e1s entren a la formalidad&#8221;. Entonces asegur\u00f3 que &#8220;en este caso es todo ganancia, m\u00e1s plata para las jubilaciones, m\u00e1s para las obras sociales&#8221;.<\/p>\n\n\n\n<p>Adem\u00e1s, Bullrich cuestion\u00f3 la &#8220;cuota solidaria&#8221; que perciben algunos gremios cuando negocian una paritaria y consiguen aumentos salariales, y explic\u00f3 que la afiliaci\u00f3n al sindicato &#8220;en la Argentina es voluntaria y va a seguir as\u00ed, por eso hay tan pocos afiliados&#8221;.<\/p>\n\n\n\n<p>&#8220;Y, como la gente dej\u00f3 de afiliarse, empezaron a tener cuotas solidarias, que firmaron los empresarios, tambi\u00e9n hay que decirlo, que son un 2, un 4 o un 5 por ciento del salario de cada trabajador&#8221;, recalc\u00f3.<\/p>\n\n\n\n<p>A modo de ejemplo, mencion\u00f3 que &#8220;un trabajador en la ley actual paga una cuota por su sepelio, pero se llega a que paga su sepelio 25 veces, es una locura&#8221;, dijo y a\u00f1adi\u00f3 que &#8220;esas cuotas hay que bajarlas porque la plata es de la gente&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta del bloque de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=4764"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4764\/revisions"}],"predecessor-version":[{"id":4766,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4764\/revisions\/4766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/4765"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=4764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=4764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=4764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}