{"id":4758,"date":"2025-12-15T22:53:29","date_gmt":"2025-12-15T22:53:29","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=4758"},"modified":"2025-12-29T21:11:47","modified_gmt":"2025-12-29T21:11:47","slug":"valdes-avanza-con-la-conformacion-de-equipos-y-sigue-de-cerca-el-tratamiento-del-presupuesto-provincial","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2025\/12\/15\/valdes-avanza-con-la-conformacion-de-equipos-y-sigue-de-cerca-el-tratamiento-del-presupuesto-provincial\/","title":{"rendered":"Vald\u00e9s avanza con la conformaci\u00f3n de equipos y sigue de cerca el tratamiento del Presupuesto provincial"},"content":{"rendered":"\n<p>El gobernador Juan Pablo Vald\u00e9s brind\u00f3 declaraciones este lunes en Casa de Gobierno, donde detall\u00f3 que en los pr\u00f3ximos d\u00edas se completar\u00e1n las designaciones en las distintas \u00e1reas del Poder Ejecutivo para cerrar la estructura de gesti\u00f3n. Asimismo, remarc\u00f3 la necesidad de aprobar el presupuesto provincial antes de fin de a\u00f1o con el objetivo de establecer la &#8220;hoja de ruta&#8221; de la administraci\u00f3n y garantizar previsibilidad.<\/p>\n\n\n\n<p>Vald\u00e9s se refiri\u00f3 a distintos temas de la actualidad al ser consultado por la prensa en Casa de Gobierno, donde brind\u00f3 precisiones sobre el armado de su equipo de gesti\u00f3n, la situaci\u00f3n presupuestaria, las medidas econ\u00f3micas en an\u00e1lisis y el v\u00ednculo con los municipios y el Gobierno nacional.<\/p>\n\n\n\n<p>En primer lugar, Vald\u00e9s destac\u00f3 el avance en la conformaci\u00f3n del gabinete provincial y subray\u00f3 que uno de los logros m\u00e1s importantes de esta etapa fue haber puesto a todos los ministros en funciones durante la primera semana de gesti\u00f3n. En ese sentido, explic\u00f3 que en la segunda semana se profundiz\u00f3 el trabajo para completar las designaciones y permitir que cada cartera cuente con sus equipos plenamente conformados. Anticip\u00f3 adem\u00e1s que en los pr\u00f3ximos d\u00edas continuar\u00e1n los nombramientos para terminar de cerrar la estructura de gobierno.<ins><\/ins><\/p>\n\n\n\n<p>En primer lugar, Vald\u00e9s destac\u00f3 el avance en la conformaci\u00f3n del gabinete provincial y subray\u00f3 que uno de los logros m\u00e1s importantes de esta etapa fue haber puesto a todos los ministros en funciones durante la primera semana de gesti\u00f3n. En ese sentido, explic\u00f3 que en la segunda semana se profundiz\u00f3 el trabajo para completar las designaciones y permitir que cada cartera cuente con sus equipos plenamente conformados. Anticip\u00f3 adem\u00e1s que en los pr\u00f3ximos d\u00edas continuar\u00e1n los nombramientos para terminar de cerrar la estructura de gobierno.<ins><\/ins><\/p>\n\n\n\n<p>En materia presupuestaria, el mandatario remarc\u00f3 la importancia de definir la &#8220;hoja de ruta&#8221; de la provincia a trav\u00e9s del presupuesto provincial, al tiempo que se\u00f1al\u00f3 la necesidad de mantener el di\u00e1logo con el Gobierno nacional en relaci\u00f3n al presupuesto nacional. Vald\u00e9s advirti\u00f3 que en el proyecto nacional se observan ausencias de inversiones consideradas estrat\u00e9gicas para Corrientes, por lo que adelant\u00f3 que se trabajar\u00e1 junto a senadores y diputados para defender los intereses de la provincia.<\/p>\n\n\n\n<p>Respecto al presupuesto provincial, enfatiz\u00f3 la necesidad de que sea aprobado antes de fin de a\u00f1o para garantizar previsibilidad y tranquilidad en la gesti\u00f3n. Cabe remarcar que el pasado viernes el ministro de Hacienda, Marcelo Rivas Piasentini se reuni\u00f3 con legisladores explicar los pormenores del proyecto.<\/p>\n\n\n\n<p>Consultado sobre la posibilidad de otorgar un bono y una canasta navide\u00f1a, el gobernador inform\u00f3 que tambi\u00e9n mantendr\u00e1 reuniones con Rivas Piasentini y el \u00e1rea de Econom\u00eda para comenzar a tomar definiciones. Si bien evit\u00f3 adelantar anuncios, asegur\u00f3 que la situaci\u00f3n se resolver\u00e1 en el transcurso de esta semana o, a m\u00e1s tardar, a comienzos de la pr\u00f3xima, con el objetivo de llevar tranquilidad a la poblaci\u00f3n.<\/p>\n\n\n\n<p>En cuanto al cierre del a\u00f1o, Vald\u00e9s afirm\u00f3 que la provincia &#8220;termina bien, ordenada y equilibrada&#8221;, y destac\u00f3 que ese escenario permite cumplir los objetivos de gesti\u00f3n sin comprometer las finanzas provinciales, apostando a la previsibilidad de cara al futuro.<\/p>\n\n\n\n<p>Sobre la situaci\u00f3n de los municipios, el gobernador se\u00f1al\u00f3 que en muchos casos atraviesan procesos de transici\u00f3n y que cada intendente deber\u00e1 evaluar con responsabilidad si est\u00e1 en condiciones de otorgar bonos u otras ayudas. Indic\u00f3 que la decisi\u00f3n es competencia de cada administraci\u00f3n municipal y que es fundamental no poner en riesgo las finanzas locales. Asimismo, recomend\u00f3 que ante eventuales dudas sobre gestiones anteriores se recurra a auditor\u00edas para contar con pruebas claras antes de avanzar con denuncias.<\/p>\n\n\n\n<p>Finalmente, el mandatario se refiri\u00f3 a gestiones ante el Gobierno nacional por la deuda con Corrientes y confirm\u00f3 que existe un plan de trabajo en marcha, a la espera de concretar reuniones pendientes. Por otra parte, el mandatario provincial y el ministro del Interior, Diego Santilli, hab\u00edan hablado sobre la posibilidad de otorgar tierras a la Provincia. En este marco, Vald\u00e9s dio cuenta que &#8220;estamos avanzando con eso y esperemos que dentro de pronto podamos tener una gran noticia para los correntinos&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Juan Pablo Vald\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-4758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=4758"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4758\/revisions"}],"predecessor-version":[{"id":4760,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4758\/revisions\/4760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/4759"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=4758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=4758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=4758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}