{"id":4260,"date":"2025-11-12T03:32:58","date_gmt":"2025-11-12T03:32:58","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=4260"},"modified":"2025-11-13T10:35:29","modified_gmt":"2025-11-13T10:35:29","slug":"femicidio-de-cecilia-strzyzowski-marcela-acuna-admitio-que-intento-encubrir-a-su-hijo-y-pidio-perdon","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2025\/11\/12\/femicidio-de-cecilia-strzyzowski-marcela-acuna-admitio-que-intento-encubrir-a-su-hijo-y-pidio-perdon\/","title":{"rendered":"Femicidio de Cecilia Strzyzowski: Marcela Acu\u00f1a admiti\u00f3 que intent\u00f3 encubrir a su hijo y pidi\u00f3 perd\u00f3n"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Entre l\u00e1grimas, pidi\u00f3 perd\u00f3n a Gloria Romero, madre de la v\u00edctima, y a los movimientos feministas. &#8220;Soy una mam\u00e1 que hizo lo incorrecto, pero me manej\u00e9 como mam\u00e1&#8221;, expres\u00f3 durante el juicio por jurados que se lleva adelante en la vecina provincia del Chaco.<\/h5>\n\n\n\n<p>En una nueva audiencia por el femicidio de Cecilia Strzyzowski, ocurrido en junio de 2023 en Chaco, Marcela Acu\u00f1a, madre de C\u00e9sar Sena \u2014principal acusado del crimen\u2014, brind\u00f3 una extensa declaraci\u00f3n en la que admiti\u00f3 haber intentado encubrir a su hijo, aunque insisti\u00f3 en su inocencia y en la de su pareja, Emerenciano Sena. Entre l\u00e1grimas, pidi\u00f3 perd\u00f3n a Gloria Romero, madre de la v\u00edctima, y a los movimientos feministas. &#8220;Soy una mam\u00e1 que hizo lo incorrecto, pero me manej\u00e9 como mam\u00e1&#8221;, expres\u00f3 con visible emoci\u00f3n.<\/p>\n\n\n\n<p>Acu\u00f1a relat\u00f3 en detalle c\u00f3mo fue su v\u00ednculo con Cecilia, con quien \u2014dijo\u2014 manten\u00eda una relaci\u00f3n &#8220;distante pero sin conflictos&#8221;. Cont\u00f3 que se enter\u00f3 del casamiento de su hijo por redes sociales y que el 2 de junio de 2023, d\u00eda en que desapareci\u00f3 la joven, vio a C\u00e9sar &#8220;extra\u00f1o y con rasgu\u00f1os&#8221;, quien le explic\u00f3 que hab\u00eda tenido una pelea con su pareja. &#8220;Me duele mucho esto. Jam\u00e1s da\u00f1ar\u00eda a una persona, a un ser humano&#8221;, afirm\u00f3 durante su exposici\u00f3n, que se extendi\u00f3 por m\u00e1s de una hora.<\/p>\n\n\n\n<p>Al reconstruir los hechos, la imputada se\u00f1al\u00f3 que ese mediod\u00eda not\u00f3 algo inusual en su vivienda: &#8220;Vi una puerta semiabierta y un bulto. Lo relacion\u00e9 con lo que hab\u00eda visto de mi hijo y sal\u00ed espantada&#8221;, sostuvo. Sin embargo, neg\u00f3 haber ordenado quemar el cuerpo de Cecilia, como sostiene la acusaci\u00f3n. &#8220;Nunca. Lo que dije fue \u2018s\u00e1quenme el problema\u2019, pero no sab\u00eda qu\u00e9 era&#8221;, asegur\u00f3. Tambi\u00e9n critic\u00f3 duramente a la Justicia, a la que acus\u00f3 de &#8220;ensuciar a su familia por intereses pol\u00edticos&#8221;.<\/p>\n\n\n\n<p>Acu\u00f1a intent\u00f3 adem\u00e1s deslindar responsabilidades de Emerenciano Sena, con quien comparti\u00f3 a\u00f1os de militancia social. &#8220;Si \u00e9l hubiera sabido algo, lo habr\u00eda llevado a la Polic\u00eda. Por eso le ped\u00ed a Fabiana que no le dijera nada. De eso tambi\u00e9n me siento muy culpable&#8221;, reconoci\u00f3. Entre sollozos, repiti\u00f3: &#8220;Que lo suelten a Emerenciano. Lo que me pase a m\u00ed no me importa. \u00bfQu\u00e9 m\u00f3vil pod\u00eda tener yo con una chica que ni conoc\u00eda? Era la que amaba a mi hijo&#8221;.<\/p>\n\n\n\n<p>En otro tramo de su declaraci\u00f3n, la mujer revel\u00f3 que su hijo se encontraba bajo tratamiento psiqui\u00e1trico. &#8220;La profesional me dijo que C\u00e9sar estaba en \u2018alarma roja\u2019. No entend\u00ed qu\u00e9 significaba, pero lo ocult\u00e9, incluso a su padre&#8221;, se\u00f1al\u00f3. Finalmente, concluy\u00f3 su declaraci\u00f3n pidiendo al jurado &#8220;justicia y comprensi\u00f3n&#8221; y reiterando su amor de madre: &#8220;Me queda una gran tarea por mi hijo, y les pido por \u00e9l&#8221;.<\/p>\n\n\n\n<p>Tras su testimonio, la Fiscal\u00eda desisti\u00f3 de hacer preguntas y el tribunal dispuso un cuarto intermedio antes de continuar con las audiencias del juicio por uno de los casos m\u00e1s conmocionantes de los \u00faltimos a\u00f1os en Chaco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre l\u00e1grimas, pidi\u00f3 perd\u00f3n a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-4260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=4260"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4260\/revisions"}],"predecessor-version":[{"id":4262,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4260\/revisions\/4262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/4261"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=4260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=4260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=4260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}