{"id":4070,"date":"2025-10-29T03:21:38","date_gmt":"2025-10-29T03:21:38","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=4070"},"modified":"2025-10-30T03:23:57","modified_gmt":"2025-10-30T03:23:57","slug":"exclusivo-lt7-cuerpos-decapitados-y-escuelas-cerradas-el-detalle-del-caos-en-rio-tras-la-operacion-contra-el-comando-vermelho","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2025\/10\/29\/exclusivo-lt7-cuerpos-decapitados-y-escuelas-cerradas-el-detalle-del-caos-en-rio-tras-la-operacion-contra-el-comando-vermelho\/","title":{"rendered":"Exclusivo LT7| &#8220;Cuerpos decapitados y escuelas cerradas&#8221;: el detalle del caos en R\u00edo tras la operaci\u00f3n contra el Comando Vermelho"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Los enfrentamientos dejaron un n\u00famero total a\u00fan no confirmado de\u00a0<strong>fallecidos y heridos<\/strong>, y mantienen a la ciudad pr\u00e1cticamente paralizada. &#8220;El aparato b\u00e9lico que tiene la polic\u00eda no alcanza para enfrentar al del Comando Vermelho&#8221;, advirti\u00f3 Leticia Navarro, periodista desde el vecino pa\u00eds.<\/h5>\n\n\n\n<p>Las \u00faltimas jornadas en R\u00edo de Janeiro est\u00e1n marcadas por una fuerte escalada de violencia y tensi\u00f3n social, luego de que la Polic\u00eda Militar y la Polic\u00eda Civil iniciaran una serie de allanamientos contra integrantes del Comando Vermelho, una de las organizaciones de narcotr\u00e1fico m\u00e1s poderosas de Am\u00e9rica Latina. Los enfrentamientos dejaron un n\u00famero definitivo a\u00fan no confirmado de fallecidos y heridos, y mantienen a la ciudad pr\u00e1cticamente paralizada. Hasta el momento se sabe que son 134 las v\u00edctimas fatales aunque se espera que esta cifra ascienda en las pr\u00f3ximas horas.&nbsp;<\/p>\n\n\n\n<p>En medio de la llamada &#8220;guerra contra el narcotr\u00e1fico&#8221;, el gobierno de R\u00edo de Janeiro decidi\u00f3 intensificar su ofensiva contra esta organizaci\u00f3n criminal, surgida en la d\u00e9cada de 1970 en una prisi\u00f3n de la propia ciudad, y que con el tiempo extendi\u00f3 sus operaciones por buena parte del territorio brasile\u00f1o.<\/p>\n\n\n\n<p>Desde Brasil, la periodista Leticia Navarro, describi\u00f3 a este medio un panorama alarmante: &#8220;La ciudad amaneci\u00f3 casi paralizada. Las escuelas no est\u00e1n funcionando, los comercios permanecen cerrados y esta ma\u00f1ana se hallaron cuerpos decapitados. Todav\u00eda no termin\u00f3 la operaci\u00f3n y existe el temor de una reacci\u00f3n violenta por parte de la banda&#8221;, relat\u00f3 Navarro al programa Punto de Referencia.\u00a0<\/p>\n\n\n\n<p>La periodista confirm\u00f3 adem\u00e1s que una comitiva del gobierno de Luiz In\u00e1cio Lula da Silva se desplaz\u00f3 de urgencia a R\u00edo para participar en una reuni\u00f3n de crisis, con el objetivo de evaluar la magnitud de los hechos y definir los pasos a seguir.<\/p>\n\n\n\n<p>https:\/\/googleads.g.doubleclick.net\/pagead\/ads?client=ca-pub-9077525840741891&#038;output=html&#038;h=280&#038;adk=914659568&#038;adf=2239634074&#038;pi=t.aa~a.1320844859~i.19~rp.4&#038;w=770&#038;fwrn=4&#038;fwrnh=100&#038;lmt=1761794519&#038;rafmt=1&#038;armr=3&#038;sem=mc&#038;pwprc=9632160534&#038;ad_type=text_image&#038;format=770&#215;280&#038;url=https%3A%2F%2Fwww.lt7noticias.com%2F74314-exclusivo-lt7%257C-cuerpos-decapitados-y-escuelas-cerradas-el-detalle-del-caos-en-rio-tras-la-operacion-contra-el-comando-vermelho&#038;fwr=0&#038;pra=3&#038;rh=193&#038;rw=770&#038;rpe=1&#038;resp_fmts=3&#038;wgl=1&#038;fa=27&#038;uach=WyJXaW5kb3dzIiwiMTAuMC4wIiwieDg2IiwiIiwiMTQxLjAuMzUzNy41NyIsbnVsbCwwLG51bGwsIjY0IixbWyJNaWNyb3NvZnQgRWRnZSIsIjE0MS4wLjM1MzcuNTciXSxbIk5vdD9BX0JyYW5kIiwiOC4wLjAuMCJdLFsiQ2hyb21pdW0iLCIxNDEuMC43MzkwLjU1Il1dLDBd&#038;abgtt=6&#038;dt=1761793498605&#038;bpp=3&#038;bdt=31983&#038;idt=3&#038;shv=r20251024&#038;mjsv=m202510280101&#038;ptt=9&#038;saldr=aa&#038;abxe=1&#038;cookie=ID%3De5b0a8f488690ac5%3AT%3D1753149427%3ART%3D1761688559%3AS%3DALNI_MZqkqoYJvvnzRt3qWBpmR5bMo4IAQ&#038;gpic=UID%3D000010ecbd077627%3AT%3D1753149427%3ART%3D1761688559%3AS%3DALNI_MZybj1w7zd5_TGEna2pmT-4hezJ7g&#038;eo_id_str=ID%3De1401f1438c48956%3AT%3D1753149427%3ART%3D1761794520%3AS%3DAA-AfjalEJYcM9yVKeRM8IxrPkYI&#038;prev_fmts=0x0%2C1180x280%2C770x280&#038;nras=4&#038;correlator=293048989460&#038;frm=20&#038;pv=1&#038;u_tz=-180&#038;u_his=1&#038;u_h=720&#038;u_w=1280&#038;u_ah=690&#038;u_aw=1280&#038;u_cd=24&#038;u_sd=1.5&#038;dmc=4&#038;adx=114&#038;ady=2112&#038;biw=1248&#038;bih=604&#038;scr_x=0&#038;scr_y=0&#038;eid=31095438%2C31095509%2C95376298%2C31095493%2C95344789%2C95368093&#038;oid=2&#038;pvsid=7077054528509601&#038;tmod=735980977&#038;uas=0&#038;nvt=1&#038;ref=https%3A%2F%2Fwww.lt7noticias.com%2F&#038;fc=1408&#038;brdim=10%2C10%2C10%2C10%2C1280%2C0%2C1282%2C696%2C1260%2C604&#038;vis=1&#038;rsz=%7C%7Cs%7C&#038;abl=NS&#038;fu=128&#038;bc=31&#038;bz=1.02&#038;td=1&#038;tdf=2&#038;psd=W251bGwsbnVsbCxudWxsLDNd&#038;nt=1&#038;pgls=CAA.&#038;num_ads=1&#038;ifi=4&#038;uci=a!4&#038;btvi=3&#038;fsb=1&#038;dtd=M<\/p>\n\n\n\n<p>&#8220;Hay manifestaciones de la poblaci\u00f3n, algunas a favor y otras en contra del operativo. Estamos viviendo un caos urbano. Las diferencias pol\u00edticas e ideol\u00f3gicas est\u00e1n pesando m\u00e1s que la necesidad de seguridad de la poblaci\u00f3n&#8221;, agreg\u00f3.<\/p>\n\n\n\n<p>El Comando Vermelho controla, seg\u00fan estimaciones oficiales, alrededor del 40% del crimen organizado dentro de las favelas de R\u00edo y mantiene presencia en otras regiones del pa\u00eds, como el nordeste, el sur y el centro-oeste, llegando incluso hasta zonas pr\u00f3ximas a la frontera con Venezuela.<\/p>\n\n\n\n<p>En medio de la crisis, trascendi\u00f3 que el gobierno de Estados Unidos \u2014seg\u00fan reportes locales, en un comunicado emitido por la administraci\u00f3n de Donald Trump\u2014 inst\u00f3 a Brasil a tomar &#8220;medidas contundentes&#8221; para frenar la expansi\u00f3n del narcotr\u00e1fico.<\/p>\n\n\n\n<p>Mientras tanto, el gobierno federal eval\u00faa una posible intervenci\u00f3n de las Fuerzas Armadas, aunque por el momento no se ha anunciado ninguna decisi\u00f3n definitiva. &#8220;El aparato b\u00e9lico que tiene la polic\u00eda no alcanza para enfrentar al del Comando Vermelho&#8221;, advirti\u00f3 Navarro, quien confirm\u00f3 la creaci\u00f3n de un gabinete de crisis entre el gobierno federal y el de R\u00edo de Janeiro.<\/p>\n\n\n\n<p>La situaci\u00f3n contin\u00faa en desarrollo y las autoridades locales no descartan nuevas represalias por parte del grupo criminal en las pr\u00f3ximas horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los enfrentamientos dejaron un n\u00famero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4071,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=4070"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4070\/revisions"}],"predecessor-version":[{"id":4073,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/4070\/revisions\/4073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/4071"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=4070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=4070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=4070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}