{"id":406,"date":"2023-01-13T15:51:03","date_gmt":"2023-01-13T15:51:03","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=406"},"modified":"2023-01-13T15:51:04","modified_gmt":"2023-01-13T15:51:04","slug":"dolar-hoy-el-blue-vuelve-a-subir-marca-un-nuevo-record-y-acumula-un-alza-de-12","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2023\/01\/13\/dolar-hoy-el-blue-vuelve-a-subir-marca-un-nuevo-record-y-acumula-un-alza-de-12\/","title":{"rendered":"D\u00d3LAR HOY: EL BLUE VUELVE A SUBIR, MARCA UN NUEVO R\u00c9CORD Y ACUMULA UN ALZA DE $12"},"content":{"rendered":"\n<p>El tipo de cambio paralelo avanza $5 y marca un nuevo r\u00e9cord nominal, mientras los financieros acompa\u00f1an<\/p>\n\n\n\n<p>La escalada del d\u00f3lar blue no se detiene. Luego de que ayer se conociera que la inflaci\u00f3n en 2022 alcanz\u00f3 el valor m\u00e1s alto en 32 a\u00f1os, desde la salida de la hiperinflaci\u00f3n, el tipo de cambio paralelo abre la jornada en alza y marca un nuevo r\u00e9cord nominal.<\/p>\n\n\n\n<p>Hoy, en la informalidad de las cuevas de la City porte\u00f1a, el billete estadounidense se negocia a $366 para la punta vendedora. Es un salto de $5 frente a la rueda anterior (+1,3%), mientras que a lo largo de la semana acumula un avance de $12 (+3,4%).<\/p>\n\n\n\n<p>Las presiones alcistas tambi\u00e9n se ven reflejadas sobre los tipos de cambios financieros. El d\u00f3lar MEP aparece en pantallas a $344,30, una suba diaria de $2 (+0,6%), tras haber pegado un salto de $15 durante la jornada anterior.<\/p>\n\n\n\n<p>En tanto, el contado con liquidaci\u00f3n (CCL) se negocia en el mercado de capitales a $347,21, casi $4 m\u00e1s que el cierre previo (+1,1%). De esta forma, los financieros intentar cerrar la brecha frente al blue, que en las \u00faltimas semanas se hab\u00eda ensanchado hasta un 10%. Sin embargo, todav\u00eda los distancian $22 (6,4%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El tipo de cambio paralelo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-406","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=406"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/406\/revisions"}],"predecessor-version":[{"id":408,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/406\/revisions\/408"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}