{"id":3379,"date":"2025-09-14T04:58:42","date_gmt":"2025-09-14T04:58:42","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=3379"},"modified":"2025-09-15T05:01:23","modified_gmt":"2025-09-15T05:01:23","slug":"codigo-morse-un-lenguaje-del-siglo-xix-que-podria-salvarnos-en-el-futuro","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2025\/09\/14\/codigo-morse-un-lenguaje-del-siglo-xix-que-podria-salvarnos-en-el-futuro\/","title":{"rendered":"C\u00f3digo Morse: un lenguaje del siglo XIX que podr\u00eda salvarnos en el futuro"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Radioaficionados correntinos destacan la vigencia del c\u00f3digo Morse, el primer sistema digital de comunicaci\u00f3n, y advierten que podr\u00eda ser importante en casos de colapso de internet o telefon\u00eda celular. Experiencias internacionales y especialistas coinciden en que, a pesar de su antig\u00fcedad, sigue siendo una herramienta vital en emergencias.<\/h5>\n\n\n\n<p>En un mundo hiperconectado, donde internet y la telefon\u00eda celular parecen imprescindibles, algunos especialistas sostienen que un sistema nacido hace casi dos siglos podr\u00eda volver a tener un papel clave: el c\u00f3digo Morse.&nbsp;<\/p>\n\n\n\n<p>Creado en 1832 por Samuel Morse e implementado comercialmente en 1844, este sistema basado en&nbsp;<strong>sonidos cortos y largos (puntos y rayas)&nbsp;<\/strong>permiti\u00f3 durante m\u00e1s de un siglo transmitir mensajes de forma r\u00e1pida y universal. Fue la base de la telegraf\u00eda y, seg\u00fan expertos, el primer lenguaje digital de la historia.<\/p>\n\n\n\n<p>Fue uno de los primeros sistemas de codificaci\u00f3n que permiti\u00f3 la transmisi\u00f3n de informaci\u00f3n a largas distancias a trav\u00e9s del tel\u00e9grafo el\u00e9ctrico. Este c\u00f3digo permiti\u00f3 convertir el lenguaje en se\u00f1ales el\u00e9ctricas que pod\u00edan ser enviadas y recibidas casi instant\u00e1neamente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"694\" src=\"https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/09\/image-92.png\" alt=\"\" class=\"wp-image-3381\" srcset=\"https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/09\/image-92.png 900w, https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/09\/image-92-300x231.png 300w, https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/09\/image-92-768x592.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u201cNo es un lenguaje del pasado\u201d<\/strong><\/h2>\n\n\n\n<p>Carlos Arigossi, radioaficionado correntino jubilado pero activo en la ense\u00f1anza del Morse, rechaza la idea de que sea obsoleto:&nbsp;<strong>\u201cNo estoy de acuerdo con que sea un lenguaje del pasado<\/strong>. El c\u00f3digo Morse es el primer c\u00f3digo digital que se cre\u00f3 en Am\u00e9rica. Es un escal\u00f3n en la evoluci\u00f3n de las comunicaciones, lo mismo que hoy internet o los sistemas binarios de la inform\u00e1tica\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, recuerda que hasta hace pocas d\u00e9cadas era obligatorio conocerlo para rendir la licencia de radioaficionado e incluso los pilotos de aeronaves deb\u00edan manejarlo como parte de los protocolos internacionales:<\/p>\n\n\n\n<p>\u201cEn su momento era obligatorio conocer un nivel b\u00e1sico de Morse para rendir la licencia. Tambi\u00e9n los pilotos ten\u00edan que saberlo porque formaba parte de la seguridad a\u00e9rea\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"590\" src=\"https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/09\/image-93.png\" alt=\"\" class=\"wp-image-3382\" srcset=\"https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/09\/image-93.png 900w, https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/09\/image-93-300x197.png 300w, https:\/\/infoelnordeste.com\/wp-content\/uploads\/2025\/09\/image-93-768x503.png 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Emergencias sin internet<\/strong><\/h2>\n\n\n\n<p>Reinaldo Gallo, tambi\u00e9n experimentado radioaficionado correntino, ilustr\u00f3&nbsp;la vigencia del Morse:&nbsp;\u201cEn una tormenta fuerte se cay\u00f3 la energ\u00eda y dejaron de funcionar los celulares. Un radioaficionado ciego instal\u00f3 su antena, conect\u00f3 una bater\u00eda y con telegraf\u00eda pidi\u00f3 auxilio. Gracias a eso pudieron asistir a una ciudad inundada\u201d.<\/p>\n\n\n\n<p>Y a\u00f1adieron&nbsp;un ejemplo m\u00e1s cotidiano:&nbsp;\u201cSi vos est\u00e1s en medio del r\u00edo y tu bote se hunde,&nbsp;<strong>pod\u00e9s hacer un SOS con una linterna.<\/strong>&nbsp;Todo el mundo sabe lo que significa. Con muy poquitas cosas pod\u00e9s comunicar un pedido de ayuda\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Morse y el mundo digital<\/strong><\/h2>\n\n\n\n<p>Lejos de ser una reliquia, Arigossi destac\u00f3&nbsp;que el Morse comparte con la inform\u00e1tica actual una misma l\u00f3gica binaria:&nbsp;\u201cEl sistema binario que usan hoy las computadoras no es otra cosa que dos opciones: cero y uno. El Morse trabaja igual: sonido corto y sonido largo. Es, en definitiva,&nbsp;<strong>el primer lenguaje digital\u201d.<\/strong><\/p>\n\n\n\n<p>Existen incluso aplicaciones m\u00f3viles que permiten practicarlo:&nbsp;\u201cHay apps en las que configur\u00e1s velocidad y tono, y con el dedo vas transmitiendo. As\u00ed se puede aprender jugando\u201d.<\/p>\n\n\n\n<p>El Morse tambi\u00e9n se vale de c\u00f3digos abreviados que lo hacen m\u00e1s \u00e1gil y universal:&nbsp;\u201cCon tres letras pod\u00e9s decir much\u00edsimo.<strong>&nbsp;QRQ significa urgente, RPT repetir, QSL comprendido.&nbsp;<\/strong>Es m\u00e1s r\u00e1pido y lo entiende cualquier radioaficionado del mundo, sin importar el idioma\u201d explic\u00f3 Arigossi.<\/p>\n\n\n\n<p>En la marina, en la aviaci\u00f3n y entre radioaficionados, estas claves siguen vigentes y garantizan que, aun sin un idioma com\u00fan, el mensaje sea comprendido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comunicaci\u00f3n esencial<\/strong><\/h2>\n\n\n\n<p>Para Gallo, el Morse no es solo una t\u00e9cnica, sino un s\u00edmbolo de lo humano en la comunicaci\u00f3n:&nbsp;\u201cMorse significa estar comunicado. Es di\u00e1logo, es conexi\u00f3n, aunque sea m\u00e1s lento que hablar\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Radioaficionados correntinos destacan la vigencia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,27],"tags":[],"class_list":["post-3379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-sociedad"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/3379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=3379"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/3379\/revisions"}],"predecessor-version":[{"id":3383,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/3379\/revisions\/3383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/3380"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=3379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=3379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=3379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}