{"id":3088,"date":"2025-08-24T04:13:01","date_gmt":"2025-08-24T04:13:01","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=3088"},"modified":"2025-08-25T04:14:08","modified_gmt":"2025-08-25T04:14:08","slug":"fallecio-norma-nolan-la-unica-miss-universo-argentina","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2025\/08\/24\/fallecio-norma-nolan-la-unica-miss-universo-argentina\/","title":{"rendered":"Falleci\u00f3 Norma Nolan, la \u00fanica Miss Universo argentina"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Ten\u00eda 87 a\u00f1os. Fue coronada en 1962, convirti\u00e9ndose en la primera y \u00fanica argentina en obtener el t\u00edtulo.<\/h5>\n\n\n\n<p>Norma Beatriz Nolan, la \u00fanica mujer argentina en conquistar la corona de <strong>Miss Universo<\/strong>, falleci\u00f3 a los 87 a\u00f1os. La noticia, confirmada por la organizaci\u00f3n del certamen, fue difundida mundialmente este viernes.<\/p>\n\n\n\n<p>En un emotivo mensaje, Miss Universo destac\u00f3: <em>\u201cComo la primera mujer argentina en ostentar la corona, su elegancia, belleza y esp\u00edritu pionero dejaron una huella imborrable e inspiraron a generaciones posteriores\u201d<\/em>.<\/p>\n\n\n\n<p>Nolan se consagr\u00f3 en Miami en 1962, tras imponerse entre 51 candidatas. Fue elegida por un jurado de nueve integrantes, superando a representantes de Islandia, Finlandia, Brasil y China. Antes, hab\u00eda logrado el t\u00edtulo de Miss Argentina frente a Zulma Faiad.<\/p>\n\n\n\n<p>Nacida en Venado Tuerto en 1938, estudi\u00f3 Secretariado y se desempe\u00f1\u00f3 como modelo televisiva. Durante su reinado trabaj\u00f3 con dise\u00f1adores de prestigio y fue rostro de numerosas publicidades. Radicada en Miami, mantuvo siempre un perfil bajo y resguard\u00f3 su vida privada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ten\u00eda 87 a\u00f1os. Fue coronada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-3088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/3088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=3088"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/3088\/revisions"}],"predecessor-version":[{"id":3090,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/3088\/revisions\/3090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/3089"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=3088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=3088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=3088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}