{"id":1535,"date":"2025-02-14T12:24:18","date_gmt":"2025-02-14T12:24:18","guid":{"rendered":"https:\/\/infoelnordeste.com\/?p=1535"},"modified":"2025-02-14T12:24:18","modified_gmt":"2025-02-14T12:24:18","slug":"milei-sigue-ejecutando-funcionarios-ahora-le-toco-al-titular-del-anses","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2025\/02\/14\/milei-sigue-ejecutando-funcionarios-ahora-le-toco-al-titular-del-anses\/","title":{"rendered":"MILEI SIGUE &#8220;EJECUTANDO&#8221; FUNCIONARIOS: AHORA LE TOC\u00d3 AL TITULAR DEL ANSES"},"content":{"rendered":"\n<p>&#8220;Corre por cuenta de \u00e9l&#8221;, hab\u00eda dicho esta ma\u00f1ana el mandatario y se hab\u00eda diferenciado del hasta ese momento titular del Anses, quien hab\u00eda propuesto cambiar la edad jubilatoria. &#8220;Eso no est\u00e1 en carpeta&#8221;, lo desautoriz\u00f3 Milei. Horas m\u00e1s tarde lo ech\u00f3 del organismo. &nbsp;<\/p>\n\n\n\n<p>El Gobierno desplaz\u00f3&nbsp;este lunes al&nbsp;titular de Anses, Mariano de los Heros,&nbsp;tras las tensiones que gener\u00f3 al remarcar la necesidad de avanzar en&nbsp;una reforma previsional.<\/p>\n\n\n\n<p>&#8220;Se le ha solicitado la renuncia al titular de ANSES Mariano de los Heros.&nbsp;Lo reemplazar\u00e1 Fernando Bearzi. Fin&#8221;, public\u00f3 en la red social X el vocero presidencial, Manuel Adorni.<\/p>\n\n\n\n<p>Tambi\u00e9n lo confirm\u00f3 la ministra de Capital Humano,&nbsp;Sandra Pettovello. &#8220;En el d\u00eda de hoy, se solicit\u00f3 la renuncia del titular de ANSES, Dr. Mariano de los Heros. Asumir\u00e1 el cargo de director ejecutivo Fernando Bearzi, quien hasta la fecha se desempe\u00f1aba como subdirector&#8221;, escribi\u00f3 en sus redes sociales.<\/p>\n\n\n\n<p>El&nbsp;pedido de renuncia&nbsp;se da&nbsp;luego de que Mariano de los Heros&nbsp;anunciara&nbsp;en declaraciones period\u00edsticas que el Gobierno analiza una&nbsp;reforma previsional&nbsp;que incluye una suba de la edad jubilatoria.&nbsp;<\/p>\n\n\n\n<p>El anuncio no le cay\u00f3 bien al presidente Javier Milei, que este lunes sali\u00f3 a poner pa\u00f1os fr\u00edos a los dichos del titular del Anses.&nbsp;&#8220;Corre por cuenta de \u00e9l y no es lo que est\u00e1 en carpeta&#8221;, dijo el mandatario en una entrevista televisiva, descartando que sea un objetivo para este 2025; aunque ambos coincidieron en que el sistema actual no es sostenible y apuntaron contra las jubilaciones por moratoria, cuyo \u00faltimo vencimiento ser\u00e1 el 23 de marzo y no ser\u00e1 renovada.<\/p>\n\n\n\n<p>Milei asegur\u00f3 que&nbsp;&#8220;la reforma previsional no es parte de este momento&#8221; sino que el primer objetivo es avanzar en una reforma laboral,&nbsp;con el objetivo de flexibilizar las condiciones de contrataci\u00f3n y despidos, algo que seg\u00fan el jefe de Estado impulsar\u00e1 la formalizaci\u00f3n del empleo. &#8220;Usted no puede reformar el sistema previsional si usted antes no reforma el sistema laboral.&nbsp;El kirchnerismo hizo un mont\u00f3n de aberraciones. Una de esas fue dar jubilaciones sin aportes&#8221;, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>El mandatario no descart\u00f3 avanzar en una reforma jubilatoria m\u00e1s tarde, sino que se concentr\u00f3 en criticar la decisi\u00f3n de las administraciones de Cristina Fern\u00e1ndez y Alberto Fern\u00e1ndez de sostener el plan de moratoria, que permiti\u00f3 a mujeres de entre 50 y 60 a\u00f1os y a hombres de entre 55 y 65 a\u00f1os que no llegaban a los 30 a\u00f1os de aporte completarlos a trav\u00e9s de una moratoria y poder acceder a una jubilaci\u00f3n m\u00ednima.&nbsp;<\/p>\n\n\n\n<p>&#8220;Usted tiene un pozo de donde saca el dinero, el de los aportes. Se multiplic\u00f3 el n\u00famero de manos, y entonces queda la mitad de fondos. Eso lo gener\u00f3 el kirchnerismo&#8221;, dijo Milei sobre las personas que ingresaron a ese programa, mientras que &#8220;el 40 por ciento del mercado del trabajo est\u00e1 en el sector informal&#8221;.<\/p>\n\n\n\n<p>&#8220;Primero hay que avanzar en la reforma laboral para que el sector informal se formalice, y eso va a duplicar los aportes. Esa es una forma de mejorar la jubilaci\u00f3n. Mejorarla honestamente&#8221;, prometi\u00f3 Milei, en di\u00e1logo con&nbsp;A24, aunque las condiciones laborales que busca imponer ya fueron exhibidas en el DNU 70\/2023 y frenadas por un fallo de la Justicia impulsada por la CGT.&nbsp;<\/p>\n\n\n\n<p><strong>Aumento de la edad m\u00ednima<\/strong><\/p>\n\n\n\n<p>Este fin de semana, De los Heros critic\u00f3 la jubilaci\u00f3n por moratoria, dijo que el Gobierno buscar\u00eda&nbsp;impulsar una reforma previsional \u201cantes de fin de a\u00f1o\u201d&nbsp;y que uno de los puntos a debatir ser\u00eda&nbsp;el aumento de la edad m\u00ednima para acceder a la jubilaci\u00f3n.<\/p>\n\n\n\n<p>Tambi\u00e9n se refiri\u00f3 a la posibilidad de incluir en el proyecto de reforma la&nbsp;creaci\u00f3n de una Prestaci\u00f3n de Retiro Proporcional, que consiste en una jubilaci\u00f3n seg\u00fan los a\u00f1os aportados, con la garant\u00eda de un haber m\u00ednimo equivalente a la PUAM (Prestaci\u00f3n Universal al Adulto Mayor).<\/p>\n\n\n\n<p>&#8220;El promedio de los a\u00f1os que compran por moratoria est\u00e1 arriba de los 25. O sea, es gente que ha aportado 5 a\u00f1os y 25 los compran a un precio vil. Con lo cual hay un est\u00edmulo negativo a la formalizaci\u00f3n, porque termina ganando el que se mantiene en la informalidad&#8221;, apunt\u00f3 de los Heros.<\/p>\n\n\n\n<p>Al momento de dar soluciones, el funcionario habl\u00f3 de una posible&nbsp;reforma laboral y de las cargas sociales que pagan los empleadores:&nbsp;&#8220;La informalidad tiene que ver tambi\u00e9n con los impuestos al trabajo, que es una cuesti\u00f3n que el Gobierno tambi\u00e9n est\u00e1 evaluando&#8221;, sostuvo.<\/p>\n\n\n\n<p>Para el futuro de las personas que ya no pueden acceder a la moratoria, de los Heros fue claro: &#8220;Hay gente que no llega a los 30 a\u00f1os de aportes porque ha cambiado el mundo laboral. Entonces, quien hoy no llega a los 30 a\u00f1os de aportes no tiene derecho a la jubilaci\u00f3n&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Corre por cuenta de \u00e9l&#8221;, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1536,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=1535"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1535\/revisions"}],"predecessor-version":[{"id":1537,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1535\/revisions\/1537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/1536"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=1535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=1535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=1535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}