{"id":1313,"date":"2024-12-30T11:25:20","date_gmt":"2024-12-30T11:25:20","guid":{"rendered":"https:\/\/tusnoticiasya.com\/?p=1313"},"modified":"2025-01-21T14:19:01","modified_gmt":"2025-01-21T14:19:01","slug":"un-dron-de-dos-ciudadanos-rusos-fue-hallado-en-una-terraza-del-congreso","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2024\/12\/30\/un-dron-de-dos-ciudadanos-rusos-fue-hallado-en-una-terraza-del-congreso\/","title":{"rendered":"UN DRON DE DOS CIUDADANOS RUSOS FUE HALLADO EN UNA TERRAZA DEL CONGRESO"},"content":{"rendered":"\n<p>El episodio se suma otros que involucran a personas de ese pa\u00eds en la Argentina. Se abri\u00f3 una causa judicial.<\/p>\n\n\n\n<p>El episodio ocurri\u00f3 el s\u00e1bado a la noche y termin\u00f3 en la madrugada, pasada la 1. Los protagonistas tampoco entienden del todo qu\u00e9 fue concretamente lo que pas\u00f3. Si fue un acto de espionaje, una inocente coincidencia o una burda maniobra realizada por las personas incorrectas. Lo cierto es que dos hombres de nacionalidad rusa, que iban con un carrito de beb\u00e9, se presentaron ante las puertas del Congreso para solicitar que la seguridad recuperara un dron que, dijeron que hab\u00edan &#8220;perdido&#8221;.<\/p>\n\n\n\n<p>El confuso hecho se suma a lo que ocurri\u00f3 la semana pasada, cuando dos diplom\u00e1ticos de la Embajada de Rusia se negaron a hacer un examen de alcoholemia de la direcci\u00f3n de Tr\u00e1nsito de la ciudad de Buenos Aires. Y a la revelaci\u00f3n de que dos esp\u00edas vivieron durante a\u00f1os en la Argentina y fueron recibidos con honores y condecorados por el propio Vladimir Putin por sus actividades de servicio.<\/p>\n\n\n\n<p>Lo concreto es que en la tarde del s\u00e1bado, dos rusos se presentaron en la puerta de Hip\u00f3lito Yrigoyen del Congreso Nacional para informar que se les hab\u00eda perdido el dron. No brindaron precisiones, pero pidieron poder recuperarlo. Ante esta situaci\u00f3n, y notificada la vicepresidente Victoria Villarruel, pidi\u00f3 la intervenci\u00f3n de personal de la Polic\u00eda Federal y de la Divisi\u00f3n Explosivos para hacer un rastrillaje.<\/p>\n\n\n\n<p>Los ciudadanos extranjeros dijeron que la zona donde cre\u00edan que se hab\u00eda perdido, y les pidieron al personal de seguridad del edificio que, si lo encontraban, lo entregaran en la comisar\u00eda, que all\u00ed ir\u00edan a buscarlo, seg\u00fan fuentes al tanto del hecho.<\/p>\n\n\n\n<p>Ante lo sospechoso del hecho, se despleg\u00f3 con autorizaci\u00f3n de la C\u00e1mara de Diputados para revisar cada rinc\u00f3n del edificio. Hicieron una inspecci\u00f3n por las zonas externas, terrazas y patios internos para verificar si, efectivamente, hab\u00eda sobrevolado un dron ese edificio. Se aplic\u00f3 el protocolo que rige para estos casos y, pasada la 1 de la madrugada de este domingo lo encontraron.<\/p>\n\n\n\n<p>El artefacto hallado es un dispositivo de peque\u00f1as dimensiones marca DJI, modelo Mavic minio PRO4, con una memoria marca Samsung, que tiene la capacidad de registrar im\u00e1genes y tambi\u00e9n grabar sonidos.<\/p>\n\n\n\n<p>Ante el hallazgo, de acuerdo a lo que se pudo reconstruir de las fuentes al tanto de la investigaci\u00f3n, se le dio intervenci\u00f3n a la Justicia Federal. De acuerdo a la reconstrucci\u00f3n de los hechos, ayer a la ma\u00f1ana se presentaron ante la comisar\u00eda correspondiente al Congreso tres ciudadanos de origen ruso, dos con pasaportes y uno con DNI emitido por Argentina.<\/p>\n\n\n\n<p>Este \u00faltimo, hab\u00eda ingresado en mayo y en octubre le dieron la residencia permanente: seg\u00fan la documentaci\u00f3n, se llama Pavel Bandurin, mientras que los otros dos tienen pasaporte ruso, y tienen poco m\u00e1s de 20 a\u00f1os. De los otros dos, uno fue identificado como Igor Lomakin, proveniente de Brasil, y Vitaly Kharlabo, proveniente de Etiop\u00eda. Estos \u00faltimos ten\u00edan categor\u00eda migratoria de turista.<\/p>\n\n\n\n<p>De acuerdo con la informaci\u00f3n, en el juzgado federal 2, a cargo de Sebasti\u00e1n Ramos, se procedi\u00f3 a identificar a los involucrados, y no tomar ninguna medida, hasta tanto se pueda esclarecer de manera fehaciente el hecho y las intenciones que tuvieron esos sobrevuelos en el Congreso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ESC\u00c1NDALO EN LA MA\u00d1ANA DE NAVIDAD<\/h2>\n\n\n\n<p>El confuso episodio del dron se suma a lo que ocurri\u00f3 el \u00faltimo mi\u00e9rcoles, en las primeras horas de la Navidad, cuando dos conductores de autos diplom\u00e1ticos de la Embajada de Rusia se negaron a realizar el test tras ser detenidos por agentes de tr\u00e1nsito de la Ciudad de Buenos Aires en el marco del operativo de seguridad vial del gobierno porte\u00f1o para estas Fiestas.<\/p>\n\n\n\n<p>El primer conductor de un auto diplom\u00e1tico de la embajada de Rusia, identificado como Sergei Baldin, se neg\u00f3 a realizar el control de alcoholemia alrededor de las 10.45.<\/p>\n\n\n\n<p>Baldin (38), a bordo de un Volkswagen Vento blanco con dominio &#8220;D094CSB&#8221;, no accedi\u00f3 a brindar la documentaci\u00f3n requerida por el puesto de control ni a realizar el test con el alcohol\u00edmetro para que determine el nivel exacto de alcohol en sangre.<\/p>\n\n\n\n<p>La Polic\u00eda de la Ciudad trabaj\u00f3 en el lugar tras el llamado de los agentes de tr\u00e1nsito y, finalmente, los oficiales escoltaron al auto hasta la Embajada de Rusia.<\/p>\n\n\n\n<p>En tanto, el segundo episodio tuvo lugar una hora despu\u00e9s. El conductor del otro auto diplom\u00e1tico, un Toyota Corolla, se neg\u00f3, en el mismo control del barrio porte\u00f1o de Recolet, a realizar el test de alcoholemia.<\/p>\n\n\n\n<p>Fuentes oficiales informaron que se trata del ciudadano ruso Salomat\u00edn Cardmath.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">LOS ESP\u00cdAS QUE VIVIERON EN ARGENTINA<\/h2>\n\n\n\n<p>El a\u00f1o pasado, en tanto, se conoci\u00f3 la historia de Maria Rosa Mayer Mu\u00f1os y Ludwig Gisch, una pareja que hab\u00eda sido detenida en diciembre de 2022 en Eslovenia. A ambos se les secuestraron pasaportes argentinos.<\/p>\n\n\n\n<p>Sin embargo, luego de casi tres meses de investigaci\u00f3n, la ministra de Relaciones Exteriores de Eslovenia, Tanja Fajon, confirm\u00f3 lo que se sospechaba: Maria Rosa Mayer Mu\u00f1os y Ludwig Gisch no son argentinos, sino rusos. Y esp\u00edas.<\/p>\n\n\n\n<p>Para ocultar que en realidad eran esp\u00edas rusos de \u00e9lite, Mayer Mu\u00f1os abri\u00f3 una galer\u00eda de arte en internet, mientras que Gisch dirig\u00eda una startup inform\u00e1tica. As\u00ed camuflaron su verdadera identidad por alg\u00fan tiempo hasta que el a\u00f1o pasado una fuente an\u00f3nima alert\u00f3 a las autoridades eslovenas sobre su presencia.<\/p>\n\n\n\n<p>Gisch era quien utilizaba el pasaporte argentino. Dec\u00eda haber nacido en Namibia en 1984. Dirig\u00eda DSM&amp;IT, una empresa que ofrec\u00eda software de seguridad.<\/p>\n\n\n\n<p>Dos fuentes con conocimiento detallado del caso revelaron que Mayer Mu\u00f1os y Gisch trabajaban para el servicio de inteligencia exterior ruso SVR. A diferencia de los agentes de inteligencia rusos &#8220;legales&#8221;, estos miembros operan sin v\u00ednculos visibles con Mosc\u00fa.<\/p>\n\n\n\n<p>Finalmente, en agosto del a\u00f1o pasado, la pareja fue devuelta a Rusia en un intercambio de prisioneros. Anna Valereva Dulceva y Artem Viktorovic Dulcev (tal sus nombres verdaderos) fueron recibidos con honores por Vladimir Putin. Ambos llegaron a Mosc\u00fa junto con sus dos hijos que nacieron en Argentina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El episodio se suma otros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=1313"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1313\/revisions"}],"predecessor-version":[{"id":1507,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1313\/revisions\/1507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/1314"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=1313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=1313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=1313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}