{"id":1141,"date":"2024-12-25T23:32:42","date_gmt":"2024-12-25T23:32:42","guid":{"rendered":"https:\/\/tusnoticiasya.com\/?p=1141"},"modified":"2025-01-21T14:13:32","modified_gmt":"2025-01-21T14:13:32","slug":"la-fnchamame-lanzo-en-redes-su-chamame-challenge-de-danza","status":"publish","type":"post","link":"https:\/\/infoelnordeste.com\/index.php\/2024\/12\/25\/la-fnchamame-lanzo-en-redes-su-chamame-challenge-de-danza\/","title":{"rendered":"LA FNCHAMAM\u00c9 LANZ\u00d3 EN REDES SU CHAMAM\u00c9 CHALLENGE DE DANZA"},"content":{"rendered":"\n<p>Corrientes se prepara para vivir una celebraci\u00f3n \u00fanica y la fiesta mundial ya se vive en redes con el lanzamiento del #ChamameChallenge, un concurso que invita a bailarines, amantes del chamam\u00e9 y p\u00fablico en general a participar y competir por premios incre\u00edbles. &nbsp;<\/p>\n\n\n\n<p>La iniciativa, impulsada por el Gobierno de Corrientes, a trav\u00e9s de la Subsecretar\u00eda de Sistemas y Tecnolog\u00edas de la Informaci\u00f3n, que encabeza Federico Ojeda, junto a destacados referentes locales, busca unir tradici\u00f3n y creatividad a trav\u00e9s de las redes sociales, celebrando el esp\u00edritu del chamam\u00e9 de una manera innovadora.<\/p>\n\n\n\n<p>La 34\u00b0 Fiesta Nacional del Chamam\u00e9, 20\u00b0 Fiesta del Chamam\u00e9 del MERCOSUR y 4\u00b0 Celebraci\u00f3n Mundial, que organiza el Instituto de Cultura de Corrientes, que preside Beatriz Kunin, se desarrollar\u00e1 del 17 al 26 de enero de 2025.<\/p>\n\n\n\n<p>Chamam\u00e9 Challenge ofrece una variedad de premios para los participantes, incluyendo hospedajes exclusivos en destinos ic\u00f3nicos de la provincia como Cambyret\u00e1, Ituzaing\u00f3 y Paso de la Patria.<\/p>\n\n\n\n<p>Adem\u00e1s, los participantes podr\u00e1n ganar vouchers de Mostachos Beibi, ideales para disfrutar en familia o con amigos, y entradas para la Fiesta Nacional del Chamam\u00e9, uno de los eventos culturales m\u00e1s importantes de la regi\u00f3n.<\/p>\n\n\n\n<p>El premio especial del desaf\u00edo ser\u00e1 para el video con mayor interacci\u00f3n, que recibir\u00e1 el Trofeo Oficial del primer #ChamameChallenge y un hospedaje para cuatro personas en el exclusivo Wild Wetlands Lodge en el Portal Cambyret\u00e1, Ituzaing\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s, habr\u00e1 sorteos entre todos los participantes, con premios sorpresa de emprendimientos locales que se revelar\u00e1n en los pr\u00f3ximos d\u00edas.<\/p>\n\n\n\n<p><strong>\u00bfC\u00d3MO PARTICIPAR?<\/strong><\/p>\n\n\n\n<p>Unirse al #ChamameChallenge es f\u00e1cil: los participantes deben subir un reel a su feed de Instagram bailando una singular coreograf\u00eda fusi\u00f3n de Loly FIorini sobre un remix de &#8220;Soy Forastera&#8221; de Daiuja, etiquetar a @susticorrientes, @lolyfiorini, @daiujaok, usar el hashtag #ChamameChallenge, compartir el reel oficial del desaf\u00edo en su historia de Instagram y etiquetar a @susticorrientes.<\/p>\n\n\n\n<p>Adem\u00e1s, deben seguir todas las cuentas oficiales de los organizadores y colaboradores, incluyendo @susticorrientes, @lolyfiorini, @daiujaok, @fnchamame, @culturacorrientes, @mostachosbeibi y @camaraturismocorrientes.<\/p>\n\n\n\n<p>El #ChamameChallenge es una oportunidad perfecta para conectar con la m\u00fasica y la cultura de Corrientes, mientras se disfruta de una experiencia divertida y con grandes recompensas.<\/p>\n\n\n\n<p>\u201c\u00a1A mover el cuerpo y que comience la fiesta!\u201d, invitan los organizadores. As\u00ed que, si el chamam\u00e9 corre por tus venas, es momento de mostrar tus mejores pasos y sumarte a esta fiesta que ya est\u00e1 dando que hablar en toda la regi\u00f3n.<\/p>\n\n\n\n<p><strong>ENTRADAS EN VENTA<\/strong><\/p>\n\n\n\n<p>Cabe recordar que ya est\u00e1n disponibles las entradas para el evento, con precios de 7 mil pesos (ingreso hasta las 21:30 hs.), 9 mil pesos (sin l\u00edmite de horario) y 13 mil pesos (preferencial).<\/p>\n\n\n\n<p>Los tickets pueden adquirirse en puntos de venta f\u00edsicos como el Instituto de Cultura de Corrientes, ubicado sobre San Juan 546 de la Ciudad de Corrientes, el Museo de Ciencias Naturales &#8220;Dr. Amado Bonpland&#8221;, Av. Costanera Gral. San Mart\u00edn 100, y el Centenario Shopping Mall, Av. Ra\u00fal Alfons\u00edn 3525, as\u00ed como<\/p>\n\n\n\n<p>a trav\u00e9s de la comercializaci\u00f3n electr\u00f3nica en&nbsp;<a href=\"https:\/\/weepas.ar\/\"><strong>https:\/\/weepas.ar\/<\/strong><\/a>.<\/p>\n\n\n\n<p>Adem\u00e1s, se ofrecen beneficios para quienes compren en los puntos de venta f\u00edsicos, con un descuento del 20% para afiliados al Instituto de Previsi\u00f3n Social, y opciones de pago en cuotas y descuentos adicionales con el Banco de Corrientes.<a href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-12-25\/834831.jpg\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corrientes se prepara para vivir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/comments?post=1141"}],"version-history":[{"count":1,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1141\/revisions"}],"predecessor-version":[{"id":1452,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/posts\/1141\/revisions\/1452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media\/1142"}],"wp:attachment":[{"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/media?parent=1141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/categories?post=1141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoelnordeste.com\/index.php\/wp-json\/wp\/v2\/tags?post=1141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}